{"id":3754,"date":"2019-09-26T19:03:55","date_gmt":"2019-09-26T17:03:55","guid":{"rendered":"https:\/\/cannabisground.com\/?p=3754"},"modified":"2020-10-13T17:37:43","modified_gmt":"2020-10-13T15:37:43","slug":"marihuana-sin-olor","status":"publish","type":"post","link":"https:\/\/cannabisground.com\/es\/marihuana-sin-olor\/","title":{"rendered":"Marihuana sin olor"},"content":{"rendered":"<h2>La marihuana sin olor es lo \u00faltimo en tecnolog\u00eda de una empresa de cannabis canadiense<\/h2>\n<p><a href=\"https:\/\/ketamaseeds.net\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2334 size-full\" src=\"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/banco-de-semillas-de-cannabis-ketama-seeds-banner.jpg\" alt=\"comprar semillas de marihuana\" width=\"1024\" height=\"205\" srcset=\"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/banco-de-semillas-de-cannabis-ketama-seeds-banner.jpg 1024w, https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/banco-de-semillas-de-cannabis-ketama-seeds-banner-300x60.jpg 300w, https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/banco-de-semillas-de-cannabis-ketama-seeds-banner-768x154.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>Una compa\u00f1\u00eda de cannabis de Canad\u00e1 anunci\u00f3 hace unos d\u00edas que hab\u00eda conseguido desarrollar una tecnolog\u00eda para conseguir lo que para muchos ser\u00e1 un gran alivio: la marihuana sin olor, aunque en realidad se trata de una variedad de marihuana \u201ccasi inodora\u201d. Y es casi inodora porque la combusti\u00f3n de cualquier materia vegetal siempre producir\u00e1 olor. La diferencia entre la marihuana inodora y la marihuana convencional es que el olor de la inodora no es el t\u00edpico del cannabis que todos reconocemos.<\/p>\n<p>Seg\u00fan Mark Pellicane, director de la compa\u00f1\u00eda que ha desarrollado la tecnolog\u00eda que hay detr\u00e1s de la marihuana sin olor, han desarrollado la Purecann para evitar molestias a aquellas personas que no soportan el olor que despide el cannabis. Es verdad que hay muchas personas que no son usuarias de cannabis que no toleran el olor de la hierba e incluso a algunos consumidores tambi\u00e9n les molesta el olor acre de algunas variedades. Pellicane asegura que han desarrollado la marihuana inodora pensando en estas personas y tambi\u00e9n en las personas que no quieren ser delatados por culpa del olor que desprende el cannabis; tanto al fumarlo como al almacenarlo.<\/p>\n<p>La noticia ha creado muchas expectativas entre los consumidores de cannabis, pero tambi\u00e9n ha despertado dudas sobre su veracidad. Y es que la compa\u00f1\u00eda canadiense no ha facilitado muchos datos al respecto.<\/p>\n<p>La empresa canadiense que ha desarrollado la marihuana inodora asegura que la tecnolog\u00eda PURECANN reduce significativamente el olor del cannabis cuando se almacena y cuando se fuma. Y tambi\u00e9n tiene la ventaja de disminuir la contracci\u00f3n de garganta que produce fumar adem\u00e1s de reducir la resaca del d\u00eda despu\u00e9s.<\/p>\n<p>Seg\u00fan la compa\u00f1\u00eda que ha desarrollado la tecnolog\u00eda para conseguir la marihuana inodora, todo el proceso de consumir es igual que cuando fumamos marihuana convencional. Se fuma de la misma manera y se almacena tambi\u00e9n de la misma forma. Hay que entender que esta empresa no ha inventado un dispositivo para eliminar los olores. Lo que ha desarrollado es la tecnolog\u00eda para conseguir la marihuana inodora o casi indetectable.<\/p>\n<p>La compa\u00f1\u00eda ya tiene una licencia del Ministerio de Salud canadiense y no descarta acuerdos con otras empresas de procesamiento. Seg\u00fan su director, la compa\u00f1\u00eda ya dispone de un proveedor que distribuya la tecnolog\u00eda para la marihuana sin olor en el mercado recreativo y medicinal del cannabis.<\/p>\n<h3>Tecnolog\u00eda del cannabis inodoro<\/h3>\n<p>El olor caracter\u00edstico de la marihuana proviene de <a href=\"https:\/\/cannabisground.com\/es\/terpenos\/\">los terpenos<\/a>, que son un tipo de aceites esenciales elaborados por plantas, seg\u00fan Peter Grinspoon, m\u00e9dico del Hospital General de Massachusetts y miembro de la junta del grupo de defensa M\u00e9dicos para la regulaci\u00f3n del cannabis.<\/p>\n<p>El limoneno es un terpeno que le da a los limones, las naranjas y algunas variedades de cannabis un caracter\u00edstico olor a c\u00edtricos. Mediante la tecnolog\u00eda es posible eliminar los terpenos del cannabis, pero estos son parte importante para disfrutar del sabor. Por lo tanto, si PURECANN elimina los terpenos responsables del olor y el sabor, su marihuana inodora probablemente tendr\u00e1 un sabor bastante suave. Pellicane ha confirmado que, en efecto, para obtener la marihuana inodora los terpenos se ven afectados.<\/p>\n<p>Seg\u00fan Peter Grinspoon, m\u00e9dico del Hospital General de Massachusetts y miembro de la junta del grupo de defensa M\u00e9dicos para la regulaci\u00f3n del cannabis, los terpenos son una parte importante para el disfrute recreativo y para el uso medicinal de la marihuana. Algunos estudios han asegurado que los terpenos pueden contribuir a las propiedades medicinales de la marihuana. El linalol, por ejemplo, es un terpeno que se encuentra en algunos tipos de hierba como por ejemplo la lavanda.<\/p>\n<p>Este terpeno tiene un gran potencial antidepresivo, anticonvulsivo, antiinflamatorio y ansiol\u00edtico. Los terpenos son parte importante de las propiedades medicinales de la marihuana. Por lo tanto, quitarlos para conseguir la marihuana sin olor\u00a0 no es una buena idea desde el punto de vista medicinal aunque s\u00ed desde la perspectiva de la discreci\u00f3n. Grinspoon dijo tambi\u00e9n que es imposible hacer que el humo sea completamente inodoro porque usar calor para quemar la materia vegetal produce un olor espec\u00edfico.<\/p>\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/ketamaseeds.net\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"205\" src=\"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/banco-de-semillas-de-cannabis-ketama-seeds-banner-1024x205.jpg\" alt=\"comprar semillas de marihuana\" class=\"wp-image-2334\" srcset=\"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/banco-de-semillas-de-cannabis-ketama-seeds-banner.jpg 1024w, https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/banco-de-semillas-de-cannabis-ketama-seeds-banner-300x60.jpg 300w, https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/banco-de-semillas-de-cannabis-ketama-seeds-banner-768x154.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La marihuana sin olor es lo \u00faltimo en tecnolog\u00eda de una empresa de cannabis canadiense Una compa\u00f1\u00eda de cannabis de Canad\u00e1 anunci\u00f3 hace unos d\u00edas que hab\u00eda conseguido desarrollar una tecnolog\u00eda para conseguir lo que para muchos ser\u00e1 un gran alivio: la marihuana sin olor, aunque en realidad se trata de una variedad de marihuana [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3751,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[154],"tags":[23,187],"class_list":["post-3754","post","type-post","status-publish","format-standard","has-post-thumbnail","category-variedades-de-cannabis","tag-canada","tag-canada-es","czr-hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La marihuana inodora, llega el cannabis sin olor - Cannabis Ground<\/title>\n<meta name=\"description\" content=\"La marihuana sin olor es lo \u00faltimo en tecnolog\u00eda de una empresa. La compa\u00f1\u00eda anunci\u00f3 hace unos d\u00edas que hab\u00eda conseguido desarrollar una tecnolog\u00eda para ...\" \/>\n<meta name=\"robots\" content=\"index, nofollow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cannabisground.com\/es\/marihuana-sin-olor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La marihuana inodora, llega el cannabis sin olor - Cannabis Ground\" \/>\n<meta property=\"og:description\" content=\"La marihuana sin olor es lo \u00faltimo en tecnolog\u00eda de una empresa. La compa\u00f1\u00eda anunci\u00f3 hace unos d\u00edas que hab\u00eda conseguido desarrollar una tecnolog\u00eda para ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cannabisground.com\/es\/marihuana-sin-olor\/\" \/>\n<meta property=\"og:site_name\" content=\"Cannabis Ground\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/annabisground\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-26T17:03:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-13T15:37:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/09\/Odorless-Marijuana-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cannabis Ground\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CannabisGround\" \/>\n<meta name=\"twitter:site\" content=\"@CannabisGround\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cannabis Ground\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-sin-olor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-sin-olor\\\/\"},\"author\":{\"name\":\"Cannabis Ground\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#\\\/schema\\\/person\\\/cf294a049b5af8df3bef74e1b4b1c770\"},\"headline\":\"Marihuana sin olor\",\"datePublished\":\"2019-09-26T17:03:55+00:00\",\"dateModified\":\"2020-10-13T15:37:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-sin-olor\\\/\"},\"wordCount\":737,\"publisher\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-sin-olor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Odorless-Marijuana-2.jpg\",\"keywords\":[\"Canada\",\"Canad\u00e1\"],\"articleSection\":[\"Variedades de cannabis\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-sin-olor\\\/\",\"url\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-sin-olor\\\/\",\"name\":\"La marihuana inodora, llega el cannabis sin olor - Cannabis Ground\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-sin-olor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-sin-olor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Odorless-Marijuana-2.jpg\",\"datePublished\":\"2019-09-26T17:03:55+00:00\",\"dateModified\":\"2020-10-13T15:37:43+00:00\",\"description\":\"La marihuana sin olor es lo \u00faltimo en tecnolog\u00eda de una empresa. La compa\u00f1\u00eda anunci\u00f3 hace unos d\u00edas que hab\u00eda conseguido desarrollar una tecnolog\u00eda para ...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-sin-olor\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-sin-olor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-sin-olor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Odorless-Marijuana-2.jpg\",\"contentUrl\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Odorless-Marijuana-2.jpg\",\"width\":640,\"height\":426,\"caption\":\"Marihuana sin olor-La marihuana inodora\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-sin-olor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marihuana sin olor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/\",\"name\":\"Cannabis Ground\",\"description\":\"Marijuana and ...\",\"publisher\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#organization\",\"name\":\"Cannabis Ground\",\"url\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/cannabis-ground.jpg\",\"contentUrl\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/cannabis-ground.jpg\",\"width\":640,\"height\":168,\"caption\":\"Cannabis Ground\"},\"image\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/annabisground\\\/\",\"https:\\\/\\\/x.com\\\/CannabisGround\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#\\\/schema\\\/person\\\/cf294a049b5af8df3bef74e1b4b1c770\",\"name\":\"Cannabis Ground\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g\",\"caption\":\"Cannabis Ground\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La marihuana inodora, llega el cannabis sin olor - Cannabis Ground","description":"La marihuana sin olor es lo \u00faltimo en tecnolog\u00eda de una empresa. La compa\u00f1\u00eda anunci\u00f3 hace unos d\u00edas que hab\u00eda conseguido desarrollar una tecnolog\u00eda para ...","robots":{"index":"index","follow":"nofollow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cannabisground.com\/es\/marihuana-sin-olor\/","og_locale":"es_ES","og_type":"article","og_title":"La marihuana inodora, llega el cannabis sin olor - Cannabis Ground","og_description":"La marihuana sin olor es lo \u00faltimo en tecnolog\u00eda de una empresa. La compa\u00f1\u00eda anunci\u00f3 hace unos d\u00edas que hab\u00eda conseguido desarrollar una tecnolog\u00eda para ...","og_url":"https:\/\/cannabisground.com\/es\/marihuana-sin-olor\/","og_site_name":"Cannabis Ground","article_publisher":"https:\/\/www.facebook.com\/annabisground\/","article_published_time":"2019-09-26T17:03:55+00:00","article_modified_time":"2020-10-13T15:37:43+00:00","og_image":[{"width":640,"height":426,"url":"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/09\/Odorless-Marijuana-2.jpg","type":"image\/jpeg"}],"author":"Cannabis Ground","twitter_card":"summary_large_image","twitter_creator":"@CannabisGround","twitter_site":"@CannabisGround","twitter_misc":{"Escrito por":"Cannabis Ground","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cannabisground.com\/es\/marihuana-sin-olor\/#article","isPartOf":{"@id":"https:\/\/cannabisground.com\/es\/marihuana-sin-olor\/"},"author":{"name":"Cannabis Ground","@id":"https:\/\/cannabisground.com\/es\/#\/schema\/person\/cf294a049b5af8df3bef74e1b4b1c770"},"headline":"Marihuana sin olor","datePublished":"2019-09-26T17:03:55+00:00","dateModified":"2020-10-13T15:37:43+00:00","mainEntityOfPage":{"@id":"https:\/\/cannabisground.com\/es\/marihuana-sin-olor\/"},"wordCount":737,"publisher":{"@id":"https:\/\/cannabisground.com\/es\/#organization"},"image":{"@id":"https:\/\/cannabisground.com\/es\/marihuana-sin-olor\/#primaryimage"},"thumbnailUrl":"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/09\/Odorless-Marijuana-2.jpg","keywords":["Canada","Canad\u00e1"],"articleSection":["Variedades de cannabis"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cannabisground.com\/es\/marihuana-sin-olor\/","url":"https:\/\/cannabisground.com\/es\/marihuana-sin-olor\/","name":"La marihuana inodora, llega el cannabis sin olor - Cannabis Ground","isPartOf":{"@id":"https:\/\/cannabisground.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cannabisground.com\/es\/marihuana-sin-olor\/#primaryimage"},"image":{"@id":"https:\/\/cannabisground.com\/es\/marihuana-sin-olor\/#primaryimage"},"thumbnailUrl":"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/09\/Odorless-Marijuana-2.jpg","datePublished":"2019-09-26T17:03:55+00:00","dateModified":"2020-10-13T15:37:43+00:00","description":"La marihuana sin olor es lo \u00faltimo en tecnolog\u00eda de una empresa. La compa\u00f1\u00eda anunci\u00f3 hace unos d\u00edas que hab\u00eda conseguido desarrollar una tecnolog\u00eda para ...","breadcrumb":{"@id":"https:\/\/cannabisground.com\/es\/marihuana-sin-olor\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cannabisground.com\/es\/marihuana-sin-olor\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cannabisground.com\/es\/marihuana-sin-olor\/#primaryimage","url":"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/09\/Odorless-Marijuana-2.jpg","contentUrl":"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/09\/Odorless-Marijuana-2.jpg","width":640,"height":426,"caption":"Marihuana sin olor-La marihuana inodora"},{"@type":"BreadcrumbList","@id":"https:\/\/cannabisground.com\/es\/marihuana-sin-olor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cannabisground.com\/es\/"},{"@type":"ListItem","position":2,"name":"Marihuana sin olor"}]},{"@type":"WebSite","@id":"https:\/\/cannabisground.com\/es\/#website","url":"https:\/\/cannabisground.com\/es\/","name":"Cannabis Ground","description":"Marijuana and ...","publisher":{"@id":"https:\/\/cannabisground.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cannabisground.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cannabisground.com\/es\/#organization","name":"Cannabis Ground","url":"https:\/\/cannabisground.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cannabisground.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cannabisground.com\/wp-content\/uploads\/2018\/06\/cannabis-ground.jpg","contentUrl":"https:\/\/cannabisground.com\/wp-content\/uploads\/2018\/06\/cannabis-ground.jpg","width":640,"height":168,"caption":"Cannabis Ground"},"image":{"@id":"https:\/\/cannabisground.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/annabisground\/","https:\/\/x.com\/CannabisGround"]},{"@type":"Person","@id":"https:\/\/cannabisground.com\/es\/#\/schema\/person\/cf294a049b5af8df3bef74e1b4b1c770","name":"Cannabis Ground","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g","caption":"Cannabis Ground"}}]}},"_links":{"self":[{"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/posts\/3754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/comments?post=3754"}],"version-history":[{"count":0,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/posts\/3754\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/media\/3751"}],"wp:attachment":[{"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/media?parent=3754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/categories?post=3754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/tags?post=3754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}