{"id":3130,"date":"2019-07-08T22:28:22","date_gmt":"2019-07-08T20:28:22","guid":{"rendered":"https:\/\/cannabisground.com\/?p=3130"},"modified":"2019-07-08T22:28:25","modified_gmt":"2019-07-08T20:28:25","slug":"cannabis-en-iran","status":"publish","type":"post","link":"https:\/\/cannabisground.com\/es\/cannabis-en-iran\/","title":{"rendered":"Cannabis en Ir\u00e1n"},"content":{"rendered":"<h2>Ir\u00e1n es uno de los mejores pa\u00edses del mundo para fumar excelente hach\u00eds a precios muy baratos y sin problemas legales si tienes un poco de cuidado<\/h2>\n<p>Se cree que el cannabis es originario de las regiones de Asia Central, al norte de Ir\u00e1n. El consumo espiritual del cannabis est\u00e1 bien documentado en el antiguo Ir\u00e1n. Los textos de la religi\u00f3n de Zoroastro compilados entre el 559 BC y 379 AD hablan del bhang (cannabis) como un medio para lograr la iluminaci\u00f3n espiritual. Y la m\u00edstica secta suf\u00ed del islam tambi\u00e9n utilizaba cannabis con fines religiosos.<\/p>\n<p>Las leyes en relaci\u00f3n al cannabis son muy contradictorias en Ir\u00e1n. Por una parte, la posesi\u00f3n y el uso est\u00e1n casi despenalizados. Sin embargo, el tr\u00e1fico est\u00e1 mucho m\u00e1s castigado. Traficar con cantidades mayores a cinco kilogramos puede ser castigado con la pena de muerte, e incluso cantidades de cincuenta gramos o menos, destinadas al tr\u00e1fico, se pueden castigar con hasta cincuenta latigazos. Si el traficante de peque\u00f1as cantidades es reincidente la venta de tan solo treinta gramos de aceite de <a href=\"https:\/\/cannabisground.com\/es\/tag\/hash-es\/\">hach\u00eds<\/a> puede penalizarse con la pena de muerte.<\/p>\n<p>El cultivo de opio con el objeto de traficar se castiga con una multa si es la primera vez. Multas y entre 30 y70 azotes por una segunda vez, multa, azotes y 2-5 a\u00f1os de prisi\u00f3n si es la tercera vez y hasta pena de muerte por un cuarto delito. Sin embargo, si no es con el prop\u00f3sito de producir narc\u00f3ticos, como es el caso de la marihuana, el cultivo no siempre se penaliza. Y es que el gobierno es consciente del papel hist\u00f3rico del cannabis en el pa\u00eds.<\/p>\n<p>Ir\u00e1n comparte fronteras largas y sin controles fronterizos con Afganist\u00e1n y Pakist\u00e1n, dos de los mayores productores de hach\u00eds del mundo. Por lo tanto, es muy f\u00e1cil encontrar excelente hach\u00eds.<\/p>\n<p>Tambi\u00e9n hay marihuana de producci\u00f3n local; aunque los iran\u00edes suelen fumar hach\u00eds. Las variedades de cannabis que se cultivan en Ir\u00e1n son procedentes de bancos de semillas extranjeros. Sobre todo desde que en Estados Unidos, Canad\u00e1 y Europa los genetistas han conseguido variedades muy potentes. La afici\u00f3n por el cultivo casero de cannabis tambi\u00e9n ha llegado al pa\u00eds de los Ayatol\u00e1s.<\/p>\n<p>Curiosamente, cultivar cannabis es legal si el cultivo se hace con fines alimentarios ya que en Ir\u00e1n se comen las semillas de la marihuana. De hecho, en Teher\u00e1n hay empresas que sacan aceite de las semillas del cannabis para su venta legal.<\/p>\n<p>No obstante, una cosa es la ley y otra muy diferente es su aplicaci\u00f3n. El castigo por la posesi\u00f3n de cannabis es una multa de 1,25 D\u00f3lares por cada gramo, siempre que la cantidad no exceda de 10 o 15 gramos. Y si la cantidad es menor a 10 o 15 gramos, la polic\u00eda no te molestar\u00e1. Adem\u00e1s, es raro que la polic\u00eda moleste a un occidental por posesi\u00f3n o consumo de cannabis. Sin embargo, la precauci\u00f3n es la palabra clave en este tema.<\/p>\n<p>Aunque por lo general la polic\u00eda no molesta a los extranjeros por posesi\u00f3n o consumo de cannabis, si tienes la mala suerte de que a ti s\u00ed te molesten, puedes solucionar el problema con un peque\u00f1o soborno.<\/p>\n<p>Consumir cannabis es oficialmente ilegal. Pero en la realidad la aplicaci\u00f3n de esta ley es inexistente. En cualquier ciudad de Ir\u00e1n puedes ir fumando un porro de marihuana y la mayor\u00eda de la gente no se dar\u00e1 cuenta de qu\u00e9 es lo que est\u00e1s consumiendo. Como la gran mayor\u00eda de consumidores fuman hach\u00eds y\/u opio, la marihuana parece una droga de poca importancia en comparaci\u00f3n.<\/p>\n<h3>\u00bfD\u00f3nde comprar?<\/h3>\n<p>El hach\u00eds es muy f\u00e1cil de encontrar. Date una vuelta por los parques y ver\u00e1s grupos de j\u00f3venes charlando y fumando tranquilamente. No tengas miedo de preguntarles, ya que si ellos no te lo pueden vender, s\u00ed sabr\u00e1n alg\u00fan lugar d\u00f3nde comprarlo.<\/p>\n<p>La marihuana es un tema diferente y necesitas conocer a alguien que la cultive y\/o venda. Se vende en los mercados y en algunas calles de Teher\u00e1n occidental. Los cultivadores y\/o consumidores de marihuana tienen su sello de identidad a la hora de vestir. La mayor\u00eda de los fumadores de hierba son fans del estilo occidental y se visten como raperos o como hippies de los a\u00f1os sesenta; con el pelo largo y pantalones jeans desgastados. Si encuentras a un buen cultivador te sorprender\u00e1s de la gran calidad de su marihuana.<\/p>\n<h3>Precios aproximados del cannabis en Ir\u00e1n<\/h3>\n<p>Las gen\u00e9ticas sativas de la mejor calidad cuestan entre 3 y 4 d\u00f3lares por gramo. Las variedades \u00edndicas de gran calidad cuestan entre 3 y 4 d\u00f3lares el gramo. La puedes encontrar m\u00e1s barata, pero de peor calidad.<\/p>\n<p>En precio del hach\u00eds de Pakist\u00e1n o Afganist\u00e1n oscila entre los 3 y 3,5 d\u00f3lares por gramo.<\/p>\n<p>Un \u00faltimo consejo. Ir\u00e1n es un pa\u00eds musulm\u00e1n estricto. Aunque toleren el cannabis por motivos hist\u00f3ricos y de identidad nacional, no aceptan de ninguna manera el alcohol. Si se te ocurre beber en p\u00fablico tendr\u00e1s un serio problema.<\/p>\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/ketamaseeds.net\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"205\" src=\"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/banco-de-semillas-de-cannabis-ketama-seeds-banner-1024x205.jpg\" alt=\"banco de semillas de cannabis ketama seeds\" class=\"wp-image-2334\" srcset=\"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/banco-de-semillas-de-cannabis-ketama-seeds-banner.jpg 1024w, https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/banco-de-semillas-de-cannabis-ketama-seeds-banner-300x60.jpg 300w, https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/banco-de-semillas-de-cannabis-ketama-seeds-banner-768x154.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ir\u00e1n es uno de los mejores pa\u00edses del mundo para fumar excelente hach\u00eds a precios muy baratos y sin problemas legales si tienes un poco de cuidado Se cree que el cannabis es originario de las regiones de Asia Central, al norte de Ir\u00e1n. El consumo espiritual del cannabis est\u00e1 bien documentado en el antiguo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3127,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[27,281],"class_list":{"0":"post-3130","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-cultura","8":"tag-hash","9":"tag-iran","10":"czr-hentry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cannabis en Ir\u00e1n. Marihuana y Hach\u00eds - Cannabis Ground<\/title>\n<meta name=\"description\" content=\"Ir\u00e1n es uno de los mejores pa\u00edses para fumar excelente hach\u00eds a precios muy baratos y sin problemas legales si tienes un poco de cuidado. Cannabis en Ir\u00e1n\" \/>\n<meta name=\"robots\" content=\"index, nofollow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cannabisground.com\/es\/cannabis-en-iran\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cannabis en Ir\u00e1n. Marihuana y Hach\u00eds - Cannabis Ground\" \/>\n<meta property=\"og:description\" content=\"Ir\u00e1n es uno de los mejores pa\u00edses para fumar excelente hach\u00eds a precios muy baratos y sin problemas legales si tienes un poco de cuidado. Cannabis en Ir\u00e1n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cannabisground.com\/es\/cannabis-en-iran\/\" \/>\n<meta property=\"og:site_name\" content=\"Cannabis Ground\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/annabisground\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-08T20:28:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-08T20:28:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/07\/Cannabis-in-Iran-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"425\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cannabis Ground\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CannabisGround\" \/>\n<meta name=\"twitter:site\" content=\"@CannabisGround\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cannabis Ground\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/cannabis-en-iran\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/cannabis-en-iran\\\/\"},\"author\":{\"name\":\"Cannabis Ground\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#\\\/schema\\\/person\\\/cf294a049b5af8df3bef74e1b4b1c770\"},\"headline\":\"Cannabis en Ir\u00e1n\",\"datePublished\":\"2019-07-08T20:28:22+00:00\",\"dateModified\":\"2019-07-08T20:28:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/cannabis-en-iran\\\/\"},\"wordCount\":906,\"publisher\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/cannabis-en-iran\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Cannabis-in-Iran-2.jpg\",\"keywords\":[\"Hash\",\"Iran\"],\"articleSection\":[\"Cultura\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/cannabis-en-iran\\\/\",\"url\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/cannabis-en-iran\\\/\",\"name\":\"Cannabis en Ir\u00e1n. Marihuana y Hach\u00eds - Cannabis Ground\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/cannabis-en-iran\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/cannabis-en-iran\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Cannabis-in-Iran-2.jpg\",\"datePublished\":\"2019-07-08T20:28:22+00:00\",\"dateModified\":\"2019-07-08T20:28:25+00:00\",\"description\":\"Ir\u00e1n es uno de los mejores pa\u00edses para fumar excelente hach\u00eds a precios muy baratos y sin problemas legales si tienes un poco de cuidado. Cannabis en Ir\u00e1n\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/cannabis-en-iran\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cannabisground.com\\\/es\\\/cannabis-en-iran\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/cannabis-en-iran\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Cannabis-in-Iran-2.jpg\",\"contentUrl\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Cannabis-in-Iran-2.jpg\",\"width\":640,\"height\":425,\"caption\":\"Cannabis en Ir\u00e1n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/cannabis-en-iran\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cannabis en Ir\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/\",\"name\":\"Cannabis Ground\",\"description\":\"Marijuana and ...\",\"publisher\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#organization\",\"name\":\"Cannabis Ground\",\"url\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/cannabis-ground.jpg\",\"contentUrl\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/cannabis-ground.jpg\",\"width\":640,\"height\":168,\"caption\":\"Cannabis Ground\"},\"image\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/annabisground\\\/\",\"https:\\\/\\\/x.com\\\/CannabisGround\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#\\\/schema\\\/person\\\/cf294a049b5af8df3bef74e1b4b1c770\",\"name\":\"Cannabis Ground\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g\",\"caption\":\"Cannabis Ground\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cannabis en Ir\u00e1n. Marihuana y Hach\u00eds - Cannabis Ground","description":"Ir\u00e1n es uno de los mejores pa\u00edses para fumar excelente hach\u00eds a precios muy baratos y sin problemas legales si tienes un poco de cuidado. Cannabis en Ir\u00e1n","robots":{"index":"index","follow":"nofollow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cannabisground.com\/es\/cannabis-en-iran\/","og_locale":"es_ES","og_type":"article","og_title":"Cannabis en Ir\u00e1n. Marihuana y Hach\u00eds - Cannabis Ground","og_description":"Ir\u00e1n es uno de los mejores pa\u00edses para fumar excelente hach\u00eds a precios muy baratos y sin problemas legales si tienes un poco de cuidado. Cannabis en Ir\u00e1n","og_url":"https:\/\/cannabisground.com\/es\/cannabis-en-iran\/","og_site_name":"Cannabis Ground","article_publisher":"https:\/\/www.facebook.com\/annabisground\/","article_published_time":"2019-07-08T20:28:22+00:00","article_modified_time":"2019-07-08T20:28:25+00:00","og_image":[{"width":640,"height":425,"url":"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/07\/Cannabis-in-Iran-2.jpg","type":"image\/jpeg"}],"author":"Cannabis Ground","twitter_card":"summary_large_image","twitter_creator":"@CannabisGround","twitter_site":"@CannabisGround","twitter_misc":{"Escrito por":"Cannabis Ground","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cannabisground.com\/es\/cannabis-en-iran\/#article","isPartOf":{"@id":"https:\/\/cannabisground.com\/es\/cannabis-en-iran\/"},"author":{"name":"Cannabis Ground","@id":"https:\/\/cannabisground.com\/es\/#\/schema\/person\/cf294a049b5af8df3bef74e1b4b1c770"},"headline":"Cannabis en Ir\u00e1n","datePublished":"2019-07-08T20:28:22+00:00","dateModified":"2019-07-08T20:28:25+00:00","mainEntityOfPage":{"@id":"https:\/\/cannabisground.com\/es\/cannabis-en-iran\/"},"wordCount":906,"publisher":{"@id":"https:\/\/cannabisground.com\/es\/#organization"},"image":{"@id":"https:\/\/cannabisground.com\/es\/cannabis-en-iran\/#primaryimage"},"thumbnailUrl":"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/07\/Cannabis-in-Iran-2.jpg","keywords":["Hash","Iran"],"articleSection":["Cultura"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cannabisground.com\/es\/cannabis-en-iran\/","url":"https:\/\/cannabisground.com\/es\/cannabis-en-iran\/","name":"Cannabis en Ir\u00e1n. Marihuana y Hach\u00eds - Cannabis Ground","isPartOf":{"@id":"https:\/\/cannabisground.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cannabisground.com\/es\/cannabis-en-iran\/#primaryimage"},"image":{"@id":"https:\/\/cannabisground.com\/es\/cannabis-en-iran\/#primaryimage"},"thumbnailUrl":"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/07\/Cannabis-in-Iran-2.jpg","datePublished":"2019-07-08T20:28:22+00:00","dateModified":"2019-07-08T20:28:25+00:00","description":"Ir\u00e1n es uno de los mejores pa\u00edses para fumar excelente hach\u00eds a precios muy baratos y sin problemas legales si tienes un poco de cuidado. Cannabis en Ir\u00e1n","breadcrumb":{"@id":"https:\/\/cannabisground.com\/es\/cannabis-en-iran\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cannabisground.com\/es\/cannabis-en-iran\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cannabisground.com\/es\/cannabis-en-iran\/#primaryimage","url":"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/07\/Cannabis-in-Iran-2.jpg","contentUrl":"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/07\/Cannabis-in-Iran-2.jpg","width":640,"height":425,"caption":"Cannabis en Ir\u00e1n"},{"@type":"BreadcrumbList","@id":"https:\/\/cannabisground.com\/es\/cannabis-en-iran\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cannabisground.com\/es\/"},{"@type":"ListItem","position":2,"name":"Cannabis en Ir\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/cannabisground.com\/es\/#website","url":"https:\/\/cannabisground.com\/es\/","name":"Cannabis Ground","description":"Marijuana and ...","publisher":{"@id":"https:\/\/cannabisground.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cannabisground.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cannabisground.com\/es\/#organization","name":"Cannabis Ground","url":"https:\/\/cannabisground.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cannabisground.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cannabisground.com\/wp-content\/uploads\/2018\/06\/cannabis-ground.jpg","contentUrl":"https:\/\/cannabisground.com\/wp-content\/uploads\/2018\/06\/cannabis-ground.jpg","width":640,"height":168,"caption":"Cannabis Ground"},"image":{"@id":"https:\/\/cannabisground.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/annabisground\/","https:\/\/x.com\/CannabisGround"]},{"@type":"Person","@id":"https:\/\/cannabisground.com\/es\/#\/schema\/person\/cf294a049b5af8df3bef74e1b4b1c770","name":"Cannabis Ground","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g","caption":"Cannabis Ground"}}]}},"_links":{"self":[{"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/posts\/3130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/comments?post=3130"}],"version-history":[{"count":0,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/posts\/3130\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/media\/3127"}],"wp:attachment":[{"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/media?parent=3130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/categories?post=3130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/tags?post=3130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}