{"id":2846,"date":"2019-06-12T01:06:26","date_gmt":"2019-06-11T23:06:26","guid":{"rendered":"https:\/\/cannabisground.com\/?p=2846"},"modified":"2019-06-12T02:07:14","modified_gmt":"2019-06-12T00:07:14","slug":"marihuana-en-ruta-66","status":"publish","type":"post","link":"https:\/\/cannabisground.com\/es\/marihuana-en-ruta-66\/","title":{"rendered":"Comprar marihuana en la Ruta 66"},"content":{"rendered":"<h2>Si quieres disfrutar de un cl\u00e1sico de la cultura americana, te mostramos los lugares donde comprar tu marihuana en cada estado de la Ruta 66<\/h2>\n<p>Marihuana en la Ruta 66. Son muchos los que sue\u00f1an con poder recorrer la m\u00edtica \u201cRoute 66\u201d, tambi\u00e9n llamada \u201cThe Mother Road\u201d, que sale desde Chicago, atraviesa todo el pa\u00eds de norte a sur, y finalmente termina en <a href=\"https:\/\/cannabisground.com\/es\/tag\/california-es\/\">California<\/a>. La ruta atraviesa 8 estados: Illinois,\u00a0Missouri,\u00a0Kansas,\u00a0Oklahoma,\u00a0Texas,\u00a0Nuevo M\u00e9xico,\u00a0Arizona\u00a0y California, \u00a0con un recorrido total de 2448 millas (3939 km).<\/p>\n<p>Si adem\u00e1s viajas con un amigo y alquil\u00e1is unas Harley Davidson, te sentir\u00e1s como Henry Fonda y Dennis Hopper, los protagonistas del film \u201cEasy Rider\u201d.<\/p>\n<p>En realidad, la Ruta 66 comienza en la ciudad de Chicago (Illinois). Es una interesante ciudad para escuchar buen jazz, llenar el dep\u00f3sito de tu autom\u00f3vil y, por supuesto, visitar alg\u00fan dispensario d\u00f3nde comprar la mejor marihuana de variedades de moda como la <a href=\"https:\/\/www.ketamaseeds.com\/producto\/kemango-semillas-de-marihuana-feminizadas\" target=\"_blank\" rel=\"noopener noreferrer\">KEMANGO<\/a> u otras m\u00e1s cl\u00e1sicas como WHITE WIDOW o JACK HERER, adem\u00e1s de derivados del cannabis.<\/p>\n<p>Illinois est\u00e1 cerca de convertirse en el onceavo estado en los Estados Unidos en legalizar la compra y posesi\u00f3n de marihuana recreativa. Lo m\u00e1s probable es que suceda en este a\u00f1o 2019. Pero mientras esto sucede, si quieres comprar marihuana en un dispensario, necesitar\u00e1s de una prescripci\u00f3n m\u00e9dica.<\/p>\n<p>No obstante, te damos una lista de algunos dispensarios en Chicago d\u00f3nde podr\u00e1s comprar marihuana medicinal si tienes tu prescripci\u00f3n.<\/p>\n<p>Comenzamos la Ruta 66 en el estado de Illinois.<\/p>\n<h3>Illinois<\/h3>\n<p>El cannabis en Illinois es legal solo con fines medicinales, pero tambi\u00e9n ser\u00e1 legal para uso recreativo el 1 de enero de 2020. Vamos a ver los dispensarios d\u00f3nde poder abastecerse de marihuana en los lugares que atraviesa la Ruta 66 en este estado.<\/p>\n<h3>Chicago<\/h3>\n<h4>MOCA &#8211; Modern Cannabis Dispensary<\/h4>\n<p>Final del formulario<\/p>\n<p>Direcci\u00f3n:\u00a02847 W Fullerton Ave, Chicago, IL 60647, EE. UU.<\/p>\n<p>Horario de apertura: 12:00<\/p>\n<p>N\u00famero de tel\u00e9fono: +1773-6622<\/p>\n<h4>Mission Chicago South Shore Medical Marijuana Dispensary<\/h4>\n<p>Direcci\u00f3n:\u00a08554 S Commercial Ave, Chicago, IL 60617, EE. UU.<\/p>\n<p>Horario de apertura: lun. 10:00<\/p>\n<p>Tel\u00e9fono:\u00a0+1 833-768-4357<\/p>\n<h4>Columbia Care Illinois<\/h4>\n<p>Direcci\u00f3n:\u00a04758 N Milwaukee Ave, Chicago, IL 60630, EE. UU.<\/p>\n<p>Horario de apertura: lun. 11:00<\/p>\n<p>Tel\u00e9fono:\u00a0+1 312-948-9082<\/p>\n<h4>The Herbal Care Center<\/h4>\n<p>Direcci\u00f3n:\u00a01301 S Western Ave, Chicago, IL 60608, EE. UU.<\/p>\n<p>Horario de apertura: 10:00<\/p>\n<p>Tel\u00e9fono:\u00a0+1 773-724-4200<\/p>\n<h3>Missouri<\/h3>\n<p>El cannabis recreativo en Missouri es ilegal pero despenalizado. El uso m\u00e9dico se legaliz\u00f3 en 2018.<\/p>\n<p>Por lo tanto, al igual que en Chicago, principio de la Ruta 66, necesitas de una prescripci\u00f3n m\u00e9dica para comprar marihuana de forma legal.<\/p>\n<p>En estos momentos, no hay dispensarios activos en Missouri. Sin embargo, al menos hemos podido encontrar uno abierto en St. Louis. M\u00e1s dispensarios se abrir\u00e1n a m\u00e1s tardar en enero de 2020<\/p>\n<h4>CBD Canvas Boutique &amp; Dispensary<\/h4>\n<p>(314) 308-9122<\/p>\n<p>7168 Manchester Rd<\/p>\n<h3>Kansas<\/h3>\n<p>El cannabis recreativo es ilegal en este estado. Sin embargo, se est\u00e1n dando pasos muy importantes para aumentar el n\u00famero de condiciones para la prescripci\u00f3n del cannabis medicinal en breve. Pero de momento, no cont\u00e9is con encontrar ni dispensarios ni nada relacionado con el cannabis en Springfield, que es la ciudad de este estado por d\u00f3nde pasa la Ruta 66.<\/p>\n<h3>Oklahoma<\/h3>\n<p>El cannabis en Oklahoma ahora es legal para su posesi\u00f3n y uso con fines medicinales con una licencia emitida por el estado, mientras que el aceite de CBD derivado del c\u00e1\u00f1amo industrial es legal sin una licencia.<\/p>\n<p>La ruta pasa por la ciudad de Claremore. Veamos los dispensarios que podemos encontrar.<\/p>\n<h3>Ciudad de Claremore<\/h3>\n<h4>GNU Wellness<\/h4>\n<p>1120 W Will Rogers Blvd<\/p>\n<p>Claremore, OK<\/p>\n<p>2.69\u00a0Millas de distancia<\/p>\n<h4>OHG+<\/h4>\n<p>9954 East 21st St<\/p>\n<p>Tulsa, OK<\/p>\n<p>17.87\u00a0millas del centro<\/p>\n<h4>FlowerCraft<\/h4>\n<p>2602 S Sheridan<\/p>\n<p>Tulsa, OK<\/p>\n<p>19.93\u00a0Millas del centro<\/p>\n<h4>Healthy Buds Dispensary<\/h4>\n<p>7727 E. 21st Street<\/p>\n<p>Tulsa, OK<\/p>\n<p>19\u00a0Millas del centro<\/p>\n<h4>Ye Olde Apothecary Shoppe<\/h4>\n<p>5515 S Mingo Suite L<\/p>\n<p>Tulsa, OK<\/p>\n<p>20.18\u00a0Millas del centro<\/p>\n<h4>The Dankery Dispensary<\/h4>\n<p>8125 E 51st St<\/p>\n<p>Tulsa, OK<\/p>\n<p>20.54\u00a0Millas del centro<\/p>\n<h4>One Love Wellness<\/h4>\n<p>7709 E. 42nd Pl. #103<\/p>\n<p>Tulsa, OK<\/p>\n<p>20.22\u00a0Millas del centro<\/p>\n<h4>Oklahoma Medical Garden<\/h4>\n<p>107 S Eagle Ln<\/p>\n<p>Adair, OK<\/p>\n<p>25.62\u00a0Millas del centro<\/p>\n<h4>Native Releaf<\/h4>\n<p>14613 S Memorial Dr<\/p>\n<p>Bixby, OK<\/p>\n<p>27.73\u00a0Millas del centro<\/p>\n<h4>White Rhino<\/h4>\n<p>437 West Broadway<\/p>\n<p>Muskogee, OK<\/p>\n<p>38.8\u00a0Millas del centro<\/p>\n<h4>420 Main Dispensary<\/h4>\n<p>420 N. Main<\/p>\n<p>Muskogee, OK<\/p>\n<p>38.88\u00a0Millas de distancia<\/p>\n<p>Hay m\u00e1s dispensarios en la zona. Pero poner todos en esta lista ser\u00eda interminable. Deb\u00e9is pensar que las distancias en los Estados Unidos son largas. No obstante, con esta lista tienes los dispensarios que necesitas si pasas por la Ruta 66 en Oklahoma.<\/p>\n<h3>Texas<\/h3>\n<p>El cannabis en Texas es ilegal, para fines m\u00e9dicos y recreativos. Sin embargo, el aceite de CBD con bajo contenido de THC est\u00e1 permitido para el tratamiento de la epilepsia desde 2015.<\/p>\n<p>Se puede encontrar en algunos dispensarios. Si haces la Ruta 66, al pasar por Santa Fe puedes ver estos dispensarios.<\/p>\n<h3>Nuevo M\u00e9xico<\/h3>\n<p>El cannabis en Nuevo M\u00e9xico es ilegal para uso recreativo. Sin embargo, la despenalizaci\u00f3n comenzar\u00e1 en julio del 2019. Un proyecto de ley para legalizar el uso recreativo fue aprobado en la C\u00e1mara en marzo de 2019. De momento solo es legal la marihuana recreativa.<\/p>\n<p>En el a\u00f1o 2014 los votantes de los condados de Bernalillo y Santa Fe aprobaron la despenalizaci\u00f3n de hasta 30 gramos de cannabis.<\/p>\n<p>As\u00ed que, de momento, puedes comprar marihuana medicinal en los siguientes dispensarios:<\/p>\n<h3>Bernalillo<\/h3>\n<h4>Bernalillo Dispensary<\/h4>\n<p>255 Camino Don Tomas,<br \/>Bernalillo\u00a0NM\u00a087004\u00a0<br \/>USA<\/p>\n<p>Phone:\u00a0505-867-2504<\/p>\n<h4>Grupo Minerva Canna<\/h4>\n<p>(505) 404-8182 113<\/p>\n<p>carretera 550<\/p>\n<h4>Ultra Health Dispensary &#8211; Bernalillo<\/h4>\n<p>(505) 404-8182<\/p>\n<p>113 Highway 550<\/p>\n<h4>Raw Greens<\/h4>\n<p>(505) 433-3761<\/p>\n<p>2639 San Mateo Blvd NE<\/p>\n<p>Midtown\/University<\/p>\n<h4>Urban Wellness<\/h4>\n<p>(505) 369-0081<\/p>\n<p>2910 San Mateo Blvd NE<\/p>\n<p>A las afueras de la ciudad<\/p>\n<h4>Verdes Foundation &#8211; Rio Ranch<\/h4>\n<p>(505) 280-2814<\/p>\n<p>2320 Grande Blvd SE<\/p>\n<p>Westside<\/p>\n<h4>Everest Apothecary<\/h4>\n<p>(505) 898-2800<\/p>\n<p>9237 4th St NW<\/p>\n<p>North Valley\/Los Ranchos<\/p>\n<h4>Minerva Canna Group<\/h4>\n<p>(505) 888-2699<\/p>\n<p>7103 4th St NW<\/p>\n<p>North Valley\/Los Ranchos<\/p>\n<h4>Urban Wellness<\/h4>\n<p>(505) 369-0092<\/p>\n<p>4601 Paradise Blvd NW<\/p>\n<p>Westside<\/p>\n<h4>Sacred Garden &#8211; San Mateo<\/h4>\n<p>(505) 257-3748<\/p>\n<p>616 San Mateo Blvd Ne<\/p>\n<p>International District<\/p>\n<h4>Los Ranchos Health &amp; Wellness Natural Medicine CBD &amp; Gift Shop<\/h4>\n<p>(505) 469-7926<\/p>\n<p>6701 4th St NW<\/p>\n<p>North Valley\/Los Ranchos<\/p>\n<h3>Santa Fe<\/h3>\n<h4>Minerva<\/h4>\n<p>(505) 982-1090<\/p>\n<p>1710 Cerrillos Rd<\/p>\n<h4>Kure Cannabis<\/h4>\n<p>(505) 930-5339<\/p>\n<p>Sirven en Santa Fe y alrededores<\/p>\n<h4>Fruit of the Earth Organics<\/h4>\n<p>(505) 310-7917<\/p>\n<p>901 Early St<\/p>\n<h4>CG Corrigan<\/h4>\n<p>(505) 695-1162<\/p>\n<p>802 Early St<\/p>\n<h4>Red Barn Growers<\/h4>\n<p>(505) 780-8476<\/p>\n<p>1089 S St Francis dr<\/p>\n<h3>Shift New Mexico<br \/>\u00a0<\/h3>\n<p>(505) 438-1090<\/p>\n<p>Sirven en Santa Fe y alrededores<\/p>\n<h4>Fruit of the Earth Natural Health<\/h4>\n<p>(505) 930-5073<\/p>\n<p>903 Early St<\/p>\n<h4>Sacred Garden<\/h4>\n<p>(505) 216-9686<\/p>\n<p>Sirven a Santa Fe y alrededores<\/p>\n<h4>Best Daze<\/h4>\n<p>(505) 585-4937<\/p>\n<p>4641 Airport Rd<\/p>\n<h4>CBD Kratom Warehouse<\/h4>\n<p>(303) 676-8004<\/p>\n<p>Despachan en Santa Fe y alrededores<\/p>\n<h3>Arizona<\/h3>\n<p>El cannabis recreativo no es legal, pero s\u00ed el medicinal.<\/p>\n<p>La ruta pasa por la ciudad de Holbrock. Aqu\u00ed tienes una lista de los dispensarios.<\/p>\n<h3>Holbrook<\/h3>\n<p>Es la primera ciudad de Arizona por d\u00f3nde pasa la Ruta 66. Los dispensarios de marihuana medicinal m\u00e1s importantes son:<\/p>\n<h4>K.I.N.D. Concentrates\/High Mountain Health, LLC<\/h4>\n<p>1250 S Plaza Way<\/p>\n<p>Flagstaff,\u00a0AZ\u00a086001<\/p>\n<p>(928) 774-5467<\/p>\n<h4>Yavapai Herbal<\/h4>\n<p>6287 E Copper Hill Dr Ste A<\/p>\n<p>Prescott Vly,\u00a0AZ\u00a086314-2921<\/p>\n<p>http:\/\/yavapaiherbal.com\/about-us\/<\/p>\n<p>(928) 227-2441<\/p>\n<h4>Green Pharms Mesa<\/h4>\n<p>7235 E Hampton Ave Ste 115<\/p>\n<p>Mesa,\u00a0AZ\u00a085209-3332<\/p>\n<p>http:\/\/www.greenpharms.com\/mesa.html<\/p>\n<p>(480) 410-6705<\/p>\n<h4>MUV Dispensary<\/h4>\n<p>12620 N Cave Creek Rd #1<\/p>\n<p>Phoenix,\u00a0AZ\u00a085022-6528<\/p>\n<p>(602) 358-8771<\/p>\n<p>10:00 AM &#8211; 07:00 PM<\/p>\n<h4>Herbal Risings<\/h4>\n<p>11839 N 19th Ave<\/p>\n<p>Phoenix,\u00a0AZ\u00a085029<\/p>\n<p>(602) 476-8868<\/p>\n<h4>Mission Medical Dispensaries<\/h4>\n<p>2601 W Dunlap Ave Ste 18<\/p>\n<p>Phoenix,\u00a0AZ\u00a085021-2711<\/p>\n<p>(833) 768-4357<\/p>\n<p>08:00 AM &#8211; 10:00 PM<\/p>\n<h4>Curaleaf Arizona<\/h4>\n<p>Phoenix,\u00a0AZ\u00a085014-3232<\/p>\n<p>https:\/\/az.curaleaf.com\/<\/p>\n<p>(602) 354-3094<\/p>\n<h3>Kingman<\/h3>\n<p>Es la segunda ciudad de este estado por d\u00f3nde pasa la m\u00edtica ruta 66. Veamos algunos dispensarios.<\/p>\n<h4>Hana Kingman<\/h4>\n<p>2095 Northern Ave<br \/>Kingman, AZ 86409<\/p>\n<h4>Medusa Farms Dispensary<\/h4>\n<p>3358 E Andy Devine Ave.<br \/>Kingman, AZ 86401<\/p>\n<h3>California<\/h3>\n<p>En este estado la marihuana es legal; tanto la recreativa como la medicinal. La Ruta 66 pasa primero por la ciudad de Barstow. As\u00ed que vamos a ver qu\u00e9 dispensarios puedes encontrar en esta ciudad. Y finalmente, la 66 termina en Los \u00c1ngeles.<\/p>\n<h3>Barstow<\/h3>\n<h4>Pot Of Gold<\/h4>\n<p>(442) 235-1838<\/p>\n<p>Despacha en Barstow y los alrededores<\/p>\n<p>Jet Room<\/p>\n<p>17499 Adelanto Rd<\/p>\n<h4>Branch Paradise<\/h4>\n<p>(760) 655-6202<\/p>\n<h4>Mountain Organics<\/h4>\n<p>(951) 878-0659<\/p>\n<p>41420 Moonridge<\/p>\n<h4>Everlast Wellness<\/h4>\n<p>(760) 995-3086<\/p>\n<p>Tambi\u00e9n despachan en los alrededores<\/p>\n<h4>Green Scorpion<\/h4>\n<p>(760) 867-0888<\/p>\n<h4>American Advancement of Health<\/h4>\n<p>(909) 494-2368<\/p>\n<p>Tambi\u00e9n se despacha en las zonas adyacentes<\/p>\n<h4>OG Cannabis Medical Dispensary<\/h4>\n<p>(760) 760-4000<\/p>\n<p>Tambi\u00e9n se atiende en las zonas adyacentes<\/p>\n<h4>Medical Cannabis Educational Center<\/h4>\n<p>(760) 299-6232<\/p>\n<p>Se atiende en zonas cercanas<\/p>\n<p>\u00a0Secret Stash Xpress<\/p>\n<p>(909) 999-6063<\/p>\n<p>Se atiende tambi\u00e9n en las zonas cercanas<\/p>\n<h3 style=\"text-align: center;\">Los \u00c1ngeles<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2849\" src=\"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/06\/Buying-marijuana-on-Route-66-marihuana-en-ruta-66-2.jpg\" alt=\"Buying marijuana on Route 66-marihuana en ruta 66\" width=\"640\" height=\"426\" srcset=\"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/06\/Buying-marijuana-on-Route-66-marihuana-en-ruta-66-2.jpg 640w, https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/06\/Buying-marijuana-on-Route-66-marihuana-en-ruta-66-2-300x200.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<h4>Hollyweed<\/h4>\n<p>(323) 592-3113<\/p>\n<p>Ofrecen servicios en Los \u00c1ngeles y alrededores<\/p>\n<h4>HERB<\/h4>\n<p>(844) 437-2213<\/p>\n<p>Ofrecen servicios en Los \u00c1ngeles y alrededores<\/p>\n<h4>Kaz Collective<\/h4>\n<p>(213) 663-0251<\/p>\n<p>Ofrecen servicios en Los \u00c1ngeles y alrededores<\/p>\n<h4>Hollywood Holistic<\/h4>\n<p>(323) 499-1522<\/p>\n<p>Ofrecen servicios en Los \u00c1ngeles y alrededores<\/p>\n<h4>Pot Valet<\/h4>\n<p>(800) 357-1314<\/p>\n<p>Ofrecen servicios en Santa Monica y alrededores<\/p>\n<p>Solicita un presupuesto<\/p>\n<p>Responden, m\u00e1s o menos, en\u00a010 minutos<\/p>\n<h4>LA Meds 4 Less<\/h4>\n<p>(213) 744-9474<\/p>\n<p>1720 E 14th St<\/p>\n<p>En pleno centro de la ciudad<\/p>\n<h4>California Cannabis Melrose<\/h4>\n<p>(323) 979-2568<\/p>\n<p>Ofrecen servicios en Los \u00c1ngeles y alrededores<\/p>\n<h4>Limited Edition420<\/h4>\n<p>(323) 800-1985<\/p>\n<p>Ofrecen servicios en Los \u00c1ngeles y alrededores<\/p>\n<h4>Kushfly<\/h4>\n<p>(855) 571-0420<\/p>\n<p>Ofrecen servicios en Los \u00c1ngeles y alrededores<\/p>\n<h4>Exhale Med Center<\/h4>\n<p>(424) 279-9497<\/p>\n<p>Ofrecen servicios en Los \u00c1ngeles y alrededores<\/p>\n<p>Un viaje lleno de curiosidades y diversidad que puedes realizar consumiendo tus variedades de marihuana favoritas en la Ruta 66.<\/p>\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/ketamaseeds.net\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"205\" src=\"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/banco-de-semillas-de-cannabis-ketama-seeds-banner-1024x205.jpg\" alt=\"banco de semillas de cannabis ketama seeds\" class=\"wp-image-2334\" srcset=\"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/banco-de-semillas-de-cannabis-ketama-seeds-banner.jpg 1024w, https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/banco-de-semillas-de-cannabis-ketama-seeds-banner-300x60.jpg 300w, https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/banco-de-semillas-de-cannabis-ketama-seeds-banner-768x154.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Si quieres disfrutar de un cl\u00e1sico de la cultura americana, te mostramos los lugares donde comprar tu marihuana en cada estado de la Ruta 66 Marihuana en la Ruta 66. Son muchos los que sue\u00f1an con poder recorrer la m\u00edtica \u201cRoute 66\u201d, tambi\u00e9n llamada \u201cThe Mother Road\u201d, que sale desde Chicago, atraviesa todo el pa\u00eds [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2830,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[21,159],"class_list":["post-2846","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cultura","tag-usa","tag-usa-es","czr-hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comprar marihuana en la Ruta 66 - Cannabis Ground<\/title>\n<meta name=\"description\" content=\"Si quieres disfrutar de un cl\u00e1sico de la cultura americana, te mostramos los lugares d\u00f3nde comprar tu marihuana en cada estado de la Ruta 66\" \/>\n<meta name=\"robots\" content=\"index, nofollow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cannabisground.com\/es\/marihuana-en-ruta-66\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comprar marihuana en la Ruta 66\" \/>\n<meta property=\"og:description\" content=\"Si quieres disfrutar de un cl\u00e1sico de la cultura americana, te mostramos los lugares d\u00f3nde comprar tu marihuana en cada estado de la Ruta 66\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cannabisground.com\/es\/marihuana-en-ruta-66\/\" \/>\n<meta property=\"og:site_name\" content=\"Cannabis Ground\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/annabisground\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-11T23:06:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-12T00:07:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/06\/Buying-marijuana-on-Route-66-Comprar-marihuana-en-la-Ruta-66-2-1-1-1-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cannabis Ground\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CannabisGround\" \/>\n<meta name=\"twitter:site\" content=\"@CannabisGround\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cannabis Ground\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-en-ruta-66\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-en-ruta-66\\\/\"},\"author\":{\"name\":\"Cannabis Ground\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#\\\/schema\\\/person\\\/cf294a049b5af8df3bef74e1b4b1c770\"},\"headline\":\"Comprar marihuana en la Ruta 66\",\"datePublished\":\"2019-06-11T23:06:26+00:00\",\"dateModified\":\"2019-06-12T00:07:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-en-ruta-66\\\/\"},\"wordCount\":1531,\"publisher\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-en-ruta-66\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Buying-marijuana-on-Route-66-Comprar-marihuana-en-la-Ruta-66-2-1-1-1-1-1.jpg\",\"keywords\":[\"USA\",\"USA\"],\"articleSection\":[\"Cultura\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-en-ruta-66\\\/\",\"url\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-en-ruta-66\\\/\",\"name\":\"Comprar marihuana en la Ruta 66 - Cannabis Ground\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-en-ruta-66\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-en-ruta-66\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Buying-marijuana-on-Route-66-Comprar-marihuana-en-la-Ruta-66-2-1-1-1-1-1.jpg\",\"datePublished\":\"2019-06-11T23:06:26+00:00\",\"dateModified\":\"2019-06-12T00:07:14+00:00\",\"description\":\"Si quieres disfrutar de un cl\u00e1sico de la cultura americana, te mostramos los lugares d\u00f3nde comprar tu marihuana en cada estado de la Ruta 66\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-en-ruta-66\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-en-ruta-66\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-en-ruta-66\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Buying-marijuana-on-Route-66-Comprar-marihuana-en-la-Ruta-66-2-1-1-1-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Buying-marijuana-on-Route-66-Comprar-marihuana-en-la-Ruta-66-2-1-1-1-1-1.jpg\",\"width\":640,\"height\":426,\"caption\":\"marijuana in route 66-marihuana en ruta 66\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-en-ruta-66\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comprar marihuana en la Ruta 66\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/\",\"name\":\"Cannabis Ground\",\"description\":\"Marijuana and ...\",\"publisher\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#organization\",\"name\":\"Cannabis Ground\",\"url\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/cannabis-ground.jpg\",\"contentUrl\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/cannabis-ground.jpg\",\"width\":640,\"height\":168,\"caption\":\"Cannabis Ground\"},\"image\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/annabisground\\\/\",\"https:\\\/\\\/x.com\\\/CannabisGround\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#\\\/schema\\\/person\\\/cf294a049b5af8df3bef74e1b4b1c770\",\"name\":\"Cannabis Ground\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g\",\"caption\":\"Cannabis Ground\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comprar marihuana en la Ruta 66 - Cannabis Ground","description":"Si quieres disfrutar de un cl\u00e1sico de la cultura americana, te mostramos los lugares d\u00f3nde comprar tu marihuana en cada estado de la Ruta 66","robots":{"index":"index","follow":"nofollow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cannabisground.com\/es\/marihuana-en-ruta-66\/","og_locale":"es_ES","og_type":"article","og_title":"Comprar marihuana en la Ruta 66","og_description":"Si quieres disfrutar de un cl\u00e1sico de la cultura americana, te mostramos los lugares d\u00f3nde comprar tu marihuana en cada estado de la Ruta 66","og_url":"https:\/\/cannabisground.com\/es\/marihuana-en-ruta-66\/","og_site_name":"Cannabis Ground","article_publisher":"https:\/\/www.facebook.com\/annabisground\/","article_published_time":"2019-06-11T23:06:26+00:00","article_modified_time":"2019-06-12T00:07:14+00:00","og_image":[{"width":640,"height":426,"url":"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/06\/Buying-marijuana-on-Route-66-Comprar-marihuana-en-la-Ruta-66-2-1-1-1-1-1.jpg","type":"image\/jpeg"}],"author":"Cannabis Ground","twitter_card":"summary_large_image","twitter_creator":"@CannabisGround","twitter_site":"@CannabisGround","twitter_misc":{"Escrito por":"Cannabis Ground","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cannabisground.com\/es\/marihuana-en-ruta-66\/#article","isPartOf":{"@id":"https:\/\/cannabisground.com\/es\/marihuana-en-ruta-66\/"},"author":{"name":"Cannabis Ground","@id":"https:\/\/cannabisground.com\/es\/#\/schema\/person\/cf294a049b5af8df3bef74e1b4b1c770"},"headline":"Comprar marihuana en la Ruta 66","datePublished":"2019-06-11T23:06:26+00:00","dateModified":"2019-06-12T00:07:14+00:00","mainEntityOfPage":{"@id":"https:\/\/cannabisground.com\/es\/marihuana-en-ruta-66\/"},"wordCount":1531,"publisher":{"@id":"https:\/\/cannabisground.com\/es\/#organization"},"image":{"@id":"https:\/\/cannabisground.com\/es\/marihuana-en-ruta-66\/#primaryimage"},"thumbnailUrl":"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/06\/Buying-marijuana-on-Route-66-Comprar-marihuana-en-la-Ruta-66-2-1-1-1-1-1.jpg","keywords":["USA","USA"],"articleSection":["Cultura"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cannabisground.com\/es\/marihuana-en-ruta-66\/","url":"https:\/\/cannabisground.com\/es\/marihuana-en-ruta-66\/","name":"Comprar marihuana en la Ruta 66 - Cannabis Ground","isPartOf":{"@id":"https:\/\/cannabisground.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cannabisground.com\/es\/marihuana-en-ruta-66\/#primaryimage"},"image":{"@id":"https:\/\/cannabisground.com\/es\/marihuana-en-ruta-66\/#primaryimage"},"thumbnailUrl":"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/06\/Buying-marijuana-on-Route-66-Comprar-marihuana-en-la-Ruta-66-2-1-1-1-1-1.jpg","datePublished":"2019-06-11T23:06:26+00:00","dateModified":"2019-06-12T00:07:14+00:00","description":"Si quieres disfrutar de un cl\u00e1sico de la cultura americana, te mostramos los lugares d\u00f3nde comprar tu marihuana en cada estado de la Ruta 66","breadcrumb":{"@id":"https:\/\/cannabisground.com\/es\/marihuana-en-ruta-66\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cannabisground.com\/es\/marihuana-en-ruta-66\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cannabisground.com\/es\/marihuana-en-ruta-66\/#primaryimage","url":"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/06\/Buying-marijuana-on-Route-66-Comprar-marihuana-en-la-Ruta-66-2-1-1-1-1-1.jpg","contentUrl":"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/06\/Buying-marijuana-on-Route-66-Comprar-marihuana-en-la-Ruta-66-2-1-1-1-1-1.jpg","width":640,"height":426,"caption":"marijuana in route 66-marihuana en ruta 66"},{"@type":"BreadcrumbList","@id":"https:\/\/cannabisground.com\/es\/marihuana-en-ruta-66\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cannabisground.com\/es\/"},{"@type":"ListItem","position":2,"name":"Comprar marihuana en la Ruta 66"}]},{"@type":"WebSite","@id":"https:\/\/cannabisground.com\/es\/#website","url":"https:\/\/cannabisground.com\/es\/","name":"Cannabis Ground","description":"Marijuana and ...","publisher":{"@id":"https:\/\/cannabisground.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cannabisground.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cannabisground.com\/es\/#organization","name":"Cannabis Ground","url":"https:\/\/cannabisground.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cannabisground.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cannabisground.com\/wp-content\/uploads\/2018\/06\/cannabis-ground.jpg","contentUrl":"https:\/\/cannabisground.com\/wp-content\/uploads\/2018\/06\/cannabis-ground.jpg","width":640,"height":168,"caption":"Cannabis Ground"},"image":{"@id":"https:\/\/cannabisground.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/annabisground\/","https:\/\/x.com\/CannabisGround"]},{"@type":"Person","@id":"https:\/\/cannabisground.com\/es\/#\/schema\/person\/cf294a049b5af8df3bef74e1b4b1c770","name":"Cannabis Ground","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g","caption":"Cannabis Ground"}}]}},"_links":{"self":[{"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/posts\/2846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/comments?post=2846"}],"version-history":[{"count":0,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/posts\/2846\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/media\/2830"}],"wp:attachment":[{"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/media?parent=2846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/categories?post=2846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/tags?post=2846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}