{"id":2743,"date":"2019-06-04T20:59:36","date_gmt":"2019-06-04T18:59:36","guid":{"rendered":"https:\/\/cannabisground.com\/?p=2743"},"modified":"2019-06-04T20:59:39","modified_gmt":"2019-06-04T18:59:39","slug":"marihuana-en-el-ejercito","status":"publish","type":"post","link":"https:\/\/cannabisground.com\/es\/marihuana-en-el-ejercito\/","title":{"rendered":"El rol de la marihuana en el ej\u00e9rcito de los Estados Unidos"},"content":{"rendered":"<h2>An\u00e1lisis del importante papel de la marihuana entre las tropas de los Estados Unidos, desde la guerra de Vietnam, pasando por Irak, hasta la actualidad<\/h2>\n<p>Marihuana en el ej\u00e9rcito. Aunque el alcohol ha sido siempre la droga preferida por las tropas americanas desde su creaci\u00f3n, la marihuana se convirti\u00f3 en la segunda sustancia m\u00e1s consumida por los militares norteamericanos durante la guerra de Vietnam (1955-1975). Curiosamente, se consum\u00eda m\u00e1s en aquellos tiempos, a pesar de ser ilegal, que en la actualidad. Pero veamos todas las circunstancias que han rodeado este fen\u00f3meno desde hace m\u00e1s de cinco d\u00e9cadas.<\/p>\n<p>Sin duda alguna, el hecho de que el conflicto de Vietnam coincidiera con el apogeo de la era hippie, un fen\u00f3meno social nacido entre los j\u00f3venes de los Estados Unidos y r\u00e1pidamente exportado al resto del mundo occidental, tuvo mucho que ver con que la marihuana se convirtiese en la segunda sustancia recreativa m\u00e1s utilizada por el ej\u00e9rcito no profesional de los Estados Unidos de Am\u00e9rica.<\/p>\n<p>En efecto, la pasada d\u00e9cada de los sesenta y parte de los setenta, el rock and roll y la marihuana eran parte imprescindible de la cultura popular. Por supuesto, tambi\u00e9n se consum\u00edan otras drogas, como la coca\u00edna y la hero\u00edna. Pero al igual que hoy, eran sustancias consumidas por una minor\u00eda marginal que, afortunadamente, no representaban a ning\u00fan grupo social o cultural.<\/p>\n<p>Es muy importante tener en cuenta que en la guerra de Vietnam, los soldados iban obligados. Iban obligados a un conflicto b\u00e9lico que no entend\u00edan y con el que no se sent\u00edan identificados. Todas las circunstancias eran las id\u00f3neas para que aquellos j\u00f3venes intentaran que el tiempo pasado en aquel infierno fuera lo menos malo posible.<\/p>\n<p>La marihuana, siempre variedades sativas de gran potencia que proven\u00edan de Tailandia y otros pa\u00edses vecinos, era muy barata y, adem\u00e1s, parte de la cultura que les hab\u00eda tocado vivir. En plena guerra, la radio era el \u00fanico medio para sentirse m\u00e1s cerca de sus casas. Cada canal que sintonizaban les pon\u00edan las mejores canciones de la \u00e9poca. Un d\u00eda cualquiera, un soldado de 20 a\u00f1os americano que estuviera obligado a hacer la guerra en Vietnam, escuchaba los grandes \u00e9xitos del momento. Y casi todos esos grandes \u00e9xitos eran, de una u otra forma, una apolog\u00eda de la marihuana y la cultura hippie del pacifismo. Recordemos algunos hits de la \u00e9poca.<\/p>\n<p>Los Beatles, de quienes se dice que si se juntase toda la hierba que se hab\u00edan fumado, se podr\u00eda alimentar a toda una manada de vacas de Texas.<\/p>\n<p>Jimi Hendrix y su m\u00edtica canci\u00f3n \u201cPurple <a href=\"https:\/\/www.ketamaseeds.com\/semillas-de-marihuana\/haze\" target=\"_blank\" rel=\"noopener noreferrer\">Haze<\/a>\u201d<\/p>\n<p>Los Allman Brothers, con temas como \u201cMidnight River\u201d<\/p>\n<p>Pink Floyd, con temas como Time, del \u00e1lbum The dark side of the moon, del que ellos mismos aseguraban hab\u00eda que estar fumado para disfrutarlo al m\u00e1ximo.<\/p>\n<p>Bob Dylan, del que destaco ahora su canci\u00f3n \u00abRainy Day Woman\u00bb, que tambi\u00e9n es un homenaje a la marihuana.<\/p>\n<p>Black Sabbath. \u00bfAlguien recuerda su ya legendario tema \u00abSweet Leaf\u00bb?<\/p>\n<p>Tom Petty, con canciones tan \u201ccann\u00e1bicas\u201d como su \u00abYou Don&#8217;t Know How It Feels\u00bb<\/p>\n<p>Led Zeppelin, grupo brit\u00e1nico con temas tan hippies y \u201cmarihuaneros\u201d como \u00abGoing to California\u00bb<\/p>\n<p>The doors, cuyo nombre hac\u00eda referencia a las puertas de la percepci\u00f3n que te abre la marihuana. Su tema \u201cLight my fire\u201d es m\u00e1s que significativo.<\/p>\n<p>Y dejo por \u00faltimo a Grateful Death, grupo que con temas como \u201cDark Star\u201d, contribuy\u00f3 a la creaci\u00f3n del t\u00e9rmino 420, como referente de la marihuana.<\/p>\n<p>Podr\u00eda seguir escribiendo p\u00e1ginas al respecto. Pero basta con entender el entorno del soldado medio americano que, de forma obligada, se ve\u00eda desplazado a miles de kil\u00f3metros de su hogar, y que cada vez que encend\u00eda la radio, escuchaba rock and roll, en una constante referencia a la marihuana, sustancia muy barata y asequible para aquellos j\u00f3venes.<\/p>\n<p>Es curioso que muchos de los soldados americanos en Vietnam fumaron marihuana por primera vez en aquel pa\u00eds. Tan solo un 8% la hab\u00eda fumado antes. En el a\u00f1o 1967, solo un 29% de los soldados enviados aseguraban haber fumado marihuana. Pero en 1971 el n\u00famero hab\u00eda ascendido a un 34%.<\/p>\n<p>Pero los soldados americanos fumaban marihuana en todas partes, no solo en Vietnam. En el a\u00f1o 1971 una prestigiosa revista public\u00f3 un art\u00edculo en el que se afirmaba que m\u00e1s de 1.000 guardiamarinas de la Academia Naval de Annapolis (en EE.UU.) fumaban marihuana. Y en la misma \u00e9poca, la mitad de los soldados destinados en Alemania fumaban cannabis a diario.<\/p>\n<p>El cannabis era una gran ayuda para aquellos soldados cuyas vidas eran un infierno. La propaganda les hab\u00eda contado que su misi\u00f3n era frenar la expansi\u00f3n del comunismo en el mundo. Pero la cultura juvenil que ellos viv\u00edan a diario era la cultura de la paz y de la libertad. Y la marihuana era su forma de sentir esa existencia.<\/p>\n<p>Fueron muchos los soldados que se opon\u00edan a la guerra y que odiaban el ej\u00e9rcito. La marihuana les serv\u00eda de ayuda para conectar mejor con sus compa\u00f1eros de armas y era un veh\u00edculo que les serv\u00eda para abrirse a conversaciones dif\u00edciles, como el s\u00edndrome de estr\u00e9s postraum\u00e1tico (TEPT) o su punta de vista antibelicista.<\/p>\n<p>Por lo tanto, la marihuana se convirti\u00f3 en una especie de consigna anti b\u00e9lica. Por primara vez en la historia de los Estados Unidos, a finales de 1969, el 37% de los soldados se declaraban anti guerra en Vietnam.<\/p>\n<p>El Departamento de Defensa de los Estados Unidos se dio cuenta de que la marihuana era una sustancia que produc\u00eda un sentimiento pacifista en los consumidores. Por lo tanto, hizo lo imposible para erradicar la sustancia. Curiosamente, el mismo Departamento de Defensa no prest\u00f3 atenci\u00f3n al consumo de otras drogas, como la hero\u00edna o las anfetaminas, ya que no ten\u00edan ese efecto pacificador entre los soldados americanos.<\/p>\n<p>El 4 de julio de 1971, m\u00e1s de mil soldados veteranos del Vietnam se manifestaron en la playa de Chu Lai para protestar contra la guerra. La mayor\u00eda llevaba un porro encendido y fumaban marihuana mientras escuchaban a los m\u00fasicos que participaron en la concentraci\u00f3n: Hendrix, Dylan, los Stones y muchos m\u00e1s. Se ha considerado como la celebraci\u00f3n cann\u00e1bica m\u00e1s importante de la historia.<\/p>\n<p>Aunque fumar marihuana estaba prohibido en el ej\u00e9rcito de los Estados Unidos, los soldados continuaban consumiendo. Aunque el ej\u00e9rcito nunca mostr\u00f3 sus estad\u00edsticas, se cree que la mayor\u00eda de los soldados destinados en Vietnam fumaban marihuana a diario. De hecho, en aquellos momentos hab\u00eda m\u00e1s americanos que fumaban marihuana en Vietnam que en los Estados Unidos.<\/p>\n<p>El gobierno de Vietnam del sur, con capital en Saig\u00f3n, reaccion\u00f3 con furia al enterarse del asunto e implement\u00f3 una serie de medidas para dificultar el acceso de la marihuana. Pero el remedio fue peor que el problema porque la hero\u00edna empez\u00f3 a introducirse entre las tropas americanas.<\/p>\n<p>\u00bfOs acord\u00e1is de la pel\u00edcula de Oliver Stone llamada \u201cPlatoon\u201d (pelot\u00f3n en castellano)? En esta obra maestra del cine hay una escena en la que el soldado llamado Vito, coge una escopeta, la rellena de marihuana y todo el pelot\u00f3n se pone a fumar. La escena est\u00e1 basada en la realidad. Oliver Stone fue un soldado en la guerra del Vietnam y era parte de aquel pelot\u00f3n.<\/p>\n<p>No debemos olvidar que aquellos soldados que fueron a la guerra de Vietnam iban obligados por el gobierno. Y adem\u00e1s, la marihuana era ilegal en aquella \u00e9poca. Pero, \u00bfqu\u00e9 sucede con los marines hoy en d\u00eda? \u00bfPueden consumir marihuana?<\/p>\n<p>La realidad es que la marihuana sigue sin ser legal a nivel federal en los Estados Unidos. Por lo tanto, el ej\u00e9rcito no puede permitir su uso. Es algo dif\u00edcil de entender ya que muchos estados han legalizado su uso medicinal y\/o recreativo.<\/p>\n<p>Los estados que han legalizado el uso medicinal de la marihuana han hecho una lista de las enfermedades que pueden ser tratadas con cannabis. Estas son:<\/p>\n<p>ELA (tambi\u00e9n conocida como Enfermedad de Lou Gehrig<\/p>\n<p>C\u00e1ncer<\/p>\n<p>Dolor cr\u00f3nico<\/p>\n<p>Enfermedad de Crohn<\/p>\n<p>Glaucoma<\/p>\n<p>VIH \/ SIDA<\/p>\n<p>Enfermedad de Parkinson<\/p>\n<p>Esclerosis m\u00faltiple<\/p>\n<p>N\u00e1usea<\/p>\n<p>Trastorno por estr\u00e9s postraum\u00e1tico (TEPT)<\/p>\n<p>Lesi\u00f3n cerebral traum\u00e1tica (TMI)<\/p>\n<p>Colitis ulcerosa<\/p>\n<h3>\u00bfSe puede ingresar en el ej\u00e9rcito americano utilizando marihuana medicinal?<\/h3>\n<p>La respuesta es NO.<\/p>\n<p>Aunque muchos estados hayan legalizado la marihuana, el gobierno federal considera que es una sustancia ilegal. Por lo tanto, si eres militar en el ej\u00e9rcito de los Estados Unidos y te cogen consumiendo marihuana o simplemente en posesi\u00f3n de ella, puedes ser arrestado e incluso acabar en una prisi\u00f3n federal.<\/p>\n<p>Pero, adem\u00e1s, el cannabis es una sustancia que no produce agresividad, m\u00e1s bien todo lo contrario. En algunos pa\u00edses, los polic\u00edas anti disturbios beben grandes cantidades de alcohol antes de una intervenci\u00f3n. Porque el alcohol s\u00ed es una droga que provoca agresividad. Un soldado que combate en una guerra debe estar siempre en modo de combate.<\/p>\n<h3>Preguntas que se hacen a los candidatos a ingresar en el ej\u00e9rcito americano<\/h3>\n<p>\u00ab\u00bfAlguna vez has dependido f\u00edsica o psicol\u00f3gicamente de alguna droga o alcohol?\u00bb<\/p>\n<p>\u00ab\u00bfAlguna vez has usado drogas?\u00bb<\/p>\n<p>No hace falta que hayas sido adicto a ninguna droga. Con que las hayas probado, es raz\u00f3n suficiente para denegarte la entrada en el ej\u00e9rcito de los Estados Unidos.<\/p>\n<p>Los soldados americanos no pueden recurrir a la marihuana, ni medicinal ni recreativa, por causa de las leyes federales. No se admiten excepciones y, por desgracia, muchos soldados tienen que recurrir a drogas \u201clegales\u201d muy adictivas y peligrosas.<\/p>\n<p>Ex marines que regresaron de las guerras de Irak y Afganist\u00e1n est\u00e1n utilizando marihuana medicinal para tratar sus des\u00f3rdenes f\u00edsicos y ps\u00edquicos. Dolores cr\u00f3nicos, s\u00edndrome de estr\u00e9s post traum\u00e1tico y otros trastornos est\u00e1n siendo curados con marihuana medicinal.<\/p>\n<p>Pero tuvieron que abandonar el ej\u00e9rcito para acceder a la marihuana medicinal. Porque aquellos que contin\u00faan formando parte del ej\u00e9rcito de los Estados Unidos, est\u00e1n siendo tratados con opi\u00e1ceos muy adictivos, aunque legales.<\/p>\n<p>Estos opi\u00e1ceos legales han matado a m\u00e1s de 40000 americanos al a\u00f1o como consecuencia de las sobredosis. Los veteranos de las guerras de Irak y Afganist\u00e1n se han hecho adictos a los opi\u00e1ceos en un rango superior al doble de la media de los dem\u00e1s ciudadanos.<\/p>\n<p>Sin embargo, por el momento no parece posible que los soldados de la primera fuerza militar del mundo vayan a tener acceso legal a la marihuana.<\/p>\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/ketamaseeds.net\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"205\" src=\"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/banco-de-semillas-de-cannabis-ketama-seeds-banner-1024x205.jpg\" alt=\"banco de semillas de cannabis ketama seeds\" class=\"wp-image-2334\" srcset=\"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/banco-de-semillas-de-cannabis-ketama-seeds-banner.jpg 1024w, https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/banco-de-semillas-de-cannabis-ketama-seeds-banner-300x60.jpg 300w, https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/banco-de-semillas-de-cannabis-ketama-seeds-banner-768x154.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>An\u00e1lisis del importante papel de la marihuana entre las tropas de los Estados Unidos, desde la guerra de Vietnam, pasando por Irak, hasta la actualidad Marihuana en el ej\u00e9rcito. Aunque el alcohol ha sido siempre la droga preferida por las tropas americanas desde su creaci\u00f3n, la marihuana se convirti\u00f3 en la segunda sustancia m\u00e1s consumida [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2740,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[21],"class_list":["post-2743","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cultura","tag-usa","czr-hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El rol de la marihuana en el ej\u00e9rcito de los Estados Unidos<\/title>\n<meta name=\"description\" content=\"An\u00e1lisis del importante papel de la marihuana entre las tropas de los Estados Unidos, desde la guerra de Vietnam, pasando por Irak, hasta la actualidad.\" \/>\n<meta name=\"robots\" content=\"index, nofollow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cannabisground.com\/es\/marihuana-en-el-ejercito\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El rol de la marihuana en el ej\u00e9rcito de los Estados Unidos\" \/>\n<meta property=\"og:description\" content=\"An\u00e1lisis del importante papel de la marihuana entre las tropas de los Estados Unidos, desde la guerra de Vietnam, pasando por Irak, hasta la actualidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cannabisground.com\/es\/marihuana-en-el-ejercito\/\" \/>\n<meta property=\"og:site_name\" content=\"Cannabis Ground\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/annabisground\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-04T18:59:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-04T18:59:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/06\/The-role-of-marijuana-in-the-United-States-Army-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"425\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cannabis Ground\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CannabisGround\" \/>\n<meta name=\"twitter:site\" content=\"@CannabisGround\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cannabis Ground\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-en-el-ejercito\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-en-el-ejercito\\\/\"},\"author\":{\"name\":\"Cannabis Ground\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#\\\/schema\\\/person\\\/cf294a049b5af8df3bef74e1b4b1c770\"},\"headline\":\"El rol de la marihuana en el ej\u00e9rcito de los Estados Unidos\",\"datePublished\":\"2019-06-04T18:59:36+00:00\",\"dateModified\":\"2019-06-04T18:59:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-en-el-ejercito\\\/\"},\"wordCount\":1852,\"publisher\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-en-el-ejercito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/The-role-of-marijuana-in-the-United-States-Army-2.jpg\",\"keywords\":[\"USA\"],\"articleSection\":[\"Cultura\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-en-el-ejercito\\\/\",\"url\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-en-el-ejercito\\\/\",\"name\":\"El rol de la marihuana en el ej\u00e9rcito de los Estados Unidos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-en-el-ejercito\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-en-el-ejercito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/The-role-of-marijuana-in-the-United-States-Army-2.jpg\",\"datePublished\":\"2019-06-04T18:59:36+00:00\",\"dateModified\":\"2019-06-04T18:59:39+00:00\",\"description\":\"An\u00e1lisis del importante papel de la marihuana entre las tropas de los Estados Unidos, desde la guerra de Vietnam, pasando por Irak, hasta la actualidad.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-en-el-ejercito\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-en-el-ejercito\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-en-el-ejercito\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/The-role-of-marijuana-in-the-United-States-Army-2.jpg\",\"contentUrl\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/The-role-of-marijuana-in-the-United-States-Army-2.jpg\",\"width\":640,\"height\":425,\"caption\":\"The role of marijuana in the United States Army-marihuana en el ejercito\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/marihuana-en-el-ejercito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El rol de la marihuana en el ej\u00e9rcito de los Estados Unidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/\",\"name\":\"Cannabis Ground\",\"description\":\"Marijuana and ...\",\"publisher\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#organization\",\"name\":\"Cannabis Ground\",\"url\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/cannabis-ground.jpg\",\"contentUrl\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/cannabis-ground.jpg\",\"width\":640,\"height\":168,\"caption\":\"Cannabis Ground\"},\"image\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/annabisground\\\/\",\"https:\\\/\\\/x.com\\\/CannabisGround\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#\\\/schema\\\/person\\\/cf294a049b5af8df3bef74e1b4b1c770\",\"name\":\"Cannabis Ground\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g\",\"caption\":\"Cannabis Ground\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El rol de la marihuana en el ej\u00e9rcito de los Estados Unidos","description":"An\u00e1lisis del importante papel de la marihuana entre las tropas de los Estados Unidos, desde la guerra de Vietnam, pasando por Irak, hasta la actualidad.","robots":{"index":"index","follow":"nofollow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cannabisground.com\/es\/marihuana-en-el-ejercito\/","og_locale":"es_ES","og_type":"article","og_title":"El rol de la marihuana en el ej\u00e9rcito de los Estados Unidos","og_description":"An\u00e1lisis del importante papel de la marihuana entre las tropas de los Estados Unidos, desde la guerra de Vietnam, pasando por Irak, hasta la actualidad.","og_url":"https:\/\/cannabisground.com\/es\/marihuana-en-el-ejercito\/","og_site_name":"Cannabis Ground","article_publisher":"https:\/\/www.facebook.com\/annabisground\/","article_published_time":"2019-06-04T18:59:36+00:00","article_modified_time":"2019-06-04T18:59:39+00:00","og_image":[{"width":640,"height":425,"url":"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/06\/The-role-of-marijuana-in-the-United-States-Army-2.jpg","type":"image\/jpeg"}],"author":"Cannabis Ground","twitter_card":"summary_large_image","twitter_creator":"@CannabisGround","twitter_site":"@CannabisGround","twitter_misc":{"Escrito por":"Cannabis Ground","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cannabisground.com\/es\/marihuana-en-el-ejercito\/#article","isPartOf":{"@id":"https:\/\/cannabisground.com\/es\/marihuana-en-el-ejercito\/"},"author":{"name":"Cannabis Ground","@id":"https:\/\/cannabisground.com\/es\/#\/schema\/person\/cf294a049b5af8df3bef74e1b4b1c770"},"headline":"El rol de la marihuana en el ej\u00e9rcito de los Estados Unidos","datePublished":"2019-06-04T18:59:36+00:00","dateModified":"2019-06-04T18:59:39+00:00","mainEntityOfPage":{"@id":"https:\/\/cannabisground.com\/es\/marihuana-en-el-ejercito\/"},"wordCount":1852,"publisher":{"@id":"https:\/\/cannabisground.com\/es\/#organization"},"image":{"@id":"https:\/\/cannabisground.com\/es\/marihuana-en-el-ejercito\/#primaryimage"},"thumbnailUrl":"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/06\/The-role-of-marijuana-in-the-United-States-Army-2.jpg","keywords":["USA"],"articleSection":["Cultura"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cannabisground.com\/es\/marihuana-en-el-ejercito\/","url":"https:\/\/cannabisground.com\/es\/marihuana-en-el-ejercito\/","name":"El rol de la marihuana en el ej\u00e9rcito de los Estados Unidos","isPartOf":{"@id":"https:\/\/cannabisground.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cannabisground.com\/es\/marihuana-en-el-ejercito\/#primaryimage"},"image":{"@id":"https:\/\/cannabisground.com\/es\/marihuana-en-el-ejercito\/#primaryimage"},"thumbnailUrl":"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/06\/The-role-of-marijuana-in-the-United-States-Army-2.jpg","datePublished":"2019-06-04T18:59:36+00:00","dateModified":"2019-06-04T18:59:39+00:00","description":"An\u00e1lisis del importante papel de la marihuana entre las tropas de los Estados Unidos, desde la guerra de Vietnam, pasando por Irak, hasta la actualidad.","breadcrumb":{"@id":"https:\/\/cannabisground.com\/es\/marihuana-en-el-ejercito\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cannabisground.com\/es\/marihuana-en-el-ejercito\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cannabisground.com\/es\/marihuana-en-el-ejercito\/#primaryimage","url":"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/06\/The-role-of-marijuana-in-the-United-States-Army-2.jpg","contentUrl":"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/06\/The-role-of-marijuana-in-the-United-States-Army-2.jpg","width":640,"height":425,"caption":"The role of marijuana in the United States Army-marihuana en el ejercito"},{"@type":"BreadcrumbList","@id":"https:\/\/cannabisground.com\/es\/marihuana-en-el-ejercito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cannabisground.com\/es\/"},{"@type":"ListItem","position":2,"name":"El rol de la marihuana en el ej\u00e9rcito de los Estados Unidos"}]},{"@type":"WebSite","@id":"https:\/\/cannabisground.com\/es\/#website","url":"https:\/\/cannabisground.com\/es\/","name":"Cannabis Ground","description":"Marijuana and ...","publisher":{"@id":"https:\/\/cannabisground.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cannabisground.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cannabisground.com\/es\/#organization","name":"Cannabis Ground","url":"https:\/\/cannabisground.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cannabisground.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cannabisground.com\/wp-content\/uploads\/2018\/06\/cannabis-ground.jpg","contentUrl":"https:\/\/cannabisground.com\/wp-content\/uploads\/2018\/06\/cannabis-ground.jpg","width":640,"height":168,"caption":"Cannabis Ground"},"image":{"@id":"https:\/\/cannabisground.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/annabisground\/","https:\/\/x.com\/CannabisGround"]},{"@type":"Person","@id":"https:\/\/cannabisground.com\/es\/#\/schema\/person\/cf294a049b5af8df3bef74e1b4b1c770","name":"Cannabis Ground","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g","caption":"Cannabis Ground"}}]}},"_links":{"self":[{"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/posts\/2743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/comments?post=2743"}],"version-history":[{"count":0,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/posts\/2743\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/media\/2740"}],"wp:attachment":[{"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/media?parent=2743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/categories?post=2743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/tags?post=2743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}