{"id":2416,"date":"2019-05-13T19:05:04","date_gmt":"2019-05-13T17:05:04","guid":{"rendered":"https:\/\/cannabisground.com\/?p=2416"},"modified":"2019-05-13T19:07:30","modified_gmt":"2019-05-13T17:07:30","slug":"jim-belushi","status":"publish","type":"post","link":"https:\/\/cannabisground.com\/es\/jim-belushi\/","title":{"rendered":"Jim Belushi y su visi\u00f3n de la marihuana"},"content":{"rendered":"<h2>Jim Belushi: Si hubi\u00e9ramos sabido antes sobre el cannabis lo que sabemos ahora, muchas personas que murieron podr\u00edan seguir vivas, incluido mi hermano<\/h2>\n<p>El famoso actor Jim Belushi no es la primera celebridad que se convierte en miembro de la industria del cannabis en el mundo. Celebridades como Willie Nelson, Snoop Dogg, Tommy Chong, Damian Marley y otros est\u00e1n vendiendo marihuana gracias a sus nombres. Lo que Jim est\u00e1 haciendo es muy diferente.<\/p>\n<p>Las celebridades mencionadas han creado unas franquicias que luego venden a los vendedores de marihuana. Belushi cultiva su propia hierba en su propiedad. Y cuando decimos \u00abcrece\u00bb, lo decimos en serio. \u00c9l cultiva su marihuana con sus propias manos.<\/p>\n<p>Todo comenz\u00f3 hace tres a\u00f1os, cuando comenz\u00f3 un peque\u00f1o cultivo de cannabis medicinal. Poco a poco, abri\u00f3 una granja de marihuana recreativa con varios jardines exteriores e interiores.<\/p>\n<p>Despu\u00e9s de vender sus queridas cepas cultivadas durante un par de a\u00f1os, decidi\u00f3 poner su nombre a su marihuana. Ahora es posible comprar marihuana directamente de \u00abBelushi&#8217;s Farm\u00bb (el nombre de su marca) en Oreg\u00f3n. Por cierto, uno de sus socios es el director David Lynch.<\/p>\n<p>El actor comenz\u00f3 a fumar marihuana cuando estaba en el instituto. Sol\u00eda \u200b\u200bfumar variedades mexicanas, porque eran las m\u00e1s baratas. Dice que la marihuana que fumaba era lo suficientemente buena, con un 6 por ciento de THC. Piensa que el nivel de este cannabinoide en las nuevas cepas es demasiado alto. \u201cMe pod\u00eda fumar un porro entero. Hoy en d\u00eda no puedo. \u00a1Es demasiado fuerte!\u00bb<\/p>\n<p>Jim Belushi se hizo famoso cuando estaba participando en un programa nocturno de televisi\u00f3n llamado Saturday Night Live. Cuando el periodista Lester Black le pregunt\u00f3 si sol\u00eda fumar marihuana en ese momento, dijo que, desafortunadamente, solo beb\u00eda whisky.<\/p>\n<h3>M\u00e1s CBD que THC<\/h3>\n<p>Belushi es un consumidor moderado de marihuana. Suele dar una calada de su vaporizador tres o cuatro veces a la semana. Sin embargo, consume CDB todos los d\u00edas. \u00c9l cree que sus endocannabinoides y su homeostasis necesitan CBD para alcanzar un equilibrio perfecto.<\/p>\n<p>Como puedes leer, Belushi habla sobre la marihuana usando t\u00e9rminos m\u00e9dicos. Esto se debe a que considera que los mayores beneficios del consumo de cannabis son el tratamiento de algunas enfermedades como el Alzheimer, el trastorno postraum\u00e1tico y muchas m\u00e1s que todos conocemos. Belushi tiene dos grandes temores: la muerte y el colapso de la familia. Muchos consumidores provienen de familias rotas, sin importar si es un divorcio o una enfermedad lo que rompi\u00f3 a la familia. La familia puede colapsar cuando hay una muerte como en su familia. En cualquier caso, la vida de muchas personas se colapsa y necesitan un medicamento. El CBD es una medicina natural sin efectos secundarios adversos.<\/p>\n<p>Belushi habla de todos los veteranos que regresaron de la Segunda Guerra Mundial. Vieron cosas terribles en la guerra y trataron de ocultar su dolor detr\u00e1s de una botella de alcohol. La consecuencia es que muchas personas crecieron con padres que eran alcoh\u00f3licos y, por lo tanto, sus familias se derrumbaron. Afortunadamente, en la d\u00e9cada de 1960, apareci\u00f3 la marihuana. A pesar de que era una buena medicina, la gente sol\u00eda llamarlo \u00abdroga\u00bb.<\/p>\n<p>Su hermano era un buen jugador de f\u00fatbol que recib\u00eda varios premios cada a\u00f1o. Un d\u00eda Jim vio a su hermano en un ataque, pero no sab\u00eda qu\u00e9 era. Ahora sabe que podr\u00eda haber sido CTE (encefalopat\u00eda traum\u00e1tica cr\u00f3nica). Su hermano fue a la universidad donde ten\u00eda disponible su medicina. Pero nadie lo sab\u00eda. Todos cre\u00edan que era una droga.<\/p>\n<p>Si hubi\u00e9ramos sabido sobre el cannabis en ese momento lo que sabemos ahora, muchas personas que murieron podr\u00edan estar vivas, incluido mi hermano, dijo Belushi. Es sorprendente pensar que si su hermano John Belushi fuera un consumidor de marihuana estar\u00eda vivo hoy.<\/p>\n<p>La muerte de su hermano colaps\u00f3 su familia. Lo que no habr\u00eda pasado si su hermano hubiera podido consumir marihuana medicinal.<\/p>\n<p>La marihuana es muy \u00fatil para tratar la enfermedad de Alzheimer, dolores de cabeza, ansiedad y muchos m\u00e1s trastornos. Pero el cannabis es mucho m\u00e1s que un medicamento. La marihuana aumenta la sensaci\u00f3n que experimentamos cuando escuchamos la m\u00fasica y aumenta nuestra creatividad. Podemos degustar los alimentos que comemos con m\u00e1s placer y mejora todos nuestros sentidos. Produce un sentimiento de alegr\u00eda y abre las puertas de la conciencia.<\/p>\n<p>Cada vez que alguien le pregunta a Belushi acerca de ser otra celebridad en la industria del cannabis, como Snoop Dogg, Willie Nelson y Marley, siempre considera que hay muchas diferencias entre lo que hace y lo que hacen las celebridades mencionadas. Estas celebridades est\u00e1n etiquetando, creando franquicias. Sin embargo, Jim Belushi cultiva su propia hierba. \u00c9l tambi\u00e9n lo cura. \u00c9l es poda y recorte tambi\u00e9n. Y ahora \u00e9l est\u00e1 comercializando su marihuana.<\/p>\n<p>Belushi ama sus plantas. Ama la energ\u00eda femenina que proviene de sus variedades feminizadas. Bromea cuando dice que a todas las chicas les gusta que las mimen y las traten como si fueran reinas. Y eso es lo que hace con sus \u00abchicas\u00bb.<\/p>\n<p>Toca m\u00fasica para ellas. Durante el per\u00edodo de crecimiento, les toca reggae y, cuando las plantas est\u00e1n cerca de la cosecha, les toca m\u00fasica g\u00f3spel para que sientan que est\u00e1n viendo a Dios. Belushi realmente ama a sus plantas. Y eso se nota en el resultado final.<\/p>\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/ketamaseeds.net\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"205\" src=\"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/banco-de-semillas-de-cannabis-ketama-seeds-banner-1024x205.jpg\" alt=\"banco de semillas de cannabis ketama seeds\" class=\"wp-image-2334\" srcset=\"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/banco-de-semillas-de-cannabis-ketama-seeds-banner.jpg 1024w, https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/banco-de-semillas-de-cannabis-ketama-seeds-banner-300x60.jpg 300w, https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/banco-de-semillas-de-cannabis-ketama-seeds-banner-768x154.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Jim Belushi: Si hubi\u00e9ramos sabido antes sobre el cannabis lo que sabemos ahora, muchas personas que murieron podr\u00edan seguir vivas, incluido mi hermano El famoso actor Jim Belushi no es la primera celebridad que se convierte en miembro de la industria del cannabis en el mundo. Celebridades como Willie Nelson, Snoop Dogg, Tommy Chong, Damian [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2409,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[152],"tags":[],"class_list":["post-2416","post","type-post","status-publish","format-standard","has-post-thumbnail","category-salud","czr-hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jim Belushi y su visi\u00f3n de la marihuana - Cannabis Ground<\/title>\n<meta name=\"description\" content=\"Jim Belushi: Si hubi\u00e9ramos sabido antes sobre el cannabis lo que sabemos ahora, muchas personas que murieron podr\u00edan seguir vivas, incluido mi hermano.\" \/>\n<meta name=\"robots\" content=\"index, nofollow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cannabisground.com\/es\/jim-belushi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jim Belushi y su visi\u00f3n de la marihuana\" \/>\n<meta property=\"og:description\" content=\"Jim Belushi: Si hubi\u00e9ramos sabido antes sobre el cannabis lo que sabemos ahora, muchas personas que murieron podr\u00edan seguir vivas, incluido mi hermano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cannabisground.com\/es\/jim-belushi\/\" \/>\n<meta property=\"og:site_name\" content=\"Cannabis Ground\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/annabisground\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-13T17:05:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-13T17:07:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/Jim-Belushi-and-his-vision-of-marijuana-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cannabis Ground\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CannabisGround\" \/>\n<meta name=\"twitter:site\" content=\"@CannabisGround\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cannabis Ground\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/jim-belushi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/jim-belushi\\\/\"},\"author\":{\"name\":\"Cannabis Ground\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#\\\/schema\\\/person\\\/cf294a049b5af8df3bef74e1b4b1c770\"},\"headline\":\"Jim Belushi y su visi\u00f3n de la marihuana\",\"datePublished\":\"2019-05-13T17:05:04+00:00\",\"dateModified\":\"2019-05-13T17:07:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/jim-belushi\\\/\"},\"wordCount\":942,\"publisher\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/jim-belushi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Jim-Belushi-and-his-vision-of-marijuana-2.jpg\",\"articleSection\":[\"Salud\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/jim-belushi\\\/\",\"url\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/jim-belushi\\\/\",\"name\":\"Jim Belushi y su visi\u00f3n de la marihuana - Cannabis Ground\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/jim-belushi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/jim-belushi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Jim-Belushi-and-his-vision-of-marijuana-2.jpg\",\"datePublished\":\"2019-05-13T17:05:04+00:00\",\"dateModified\":\"2019-05-13T17:07:30+00:00\",\"description\":\"Jim Belushi: Si hubi\u00e9ramos sabido antes sobre el cannabis lo que sabemos ahora, muchas personas que murieron podr\u00edan seguir vivas, incluido mi hermano.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/jim-belushi\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cannabisground.com\\\/es\\\/jim-belushi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/jim-belushi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Jim-Belushi-and-his-vision-of-marijuana-2.jpg\",\"contentUrl\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Jim-Belushi-and-his-vision-of-marijuana-2.jpg\",\"width\":960,\"height\":960,\"caption\":\"Jim Belushi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/jim-belushi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jim Belushi y su visi\u00f3n de la marihuana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/\",\"name\":\"Cannabis Ground\",\"description\":\"Marijuana and ...\",\"publisher\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#organization\",\"name\":\"Cannabis Ground\",\"url\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/cannabis-ground.jpg\",\"contentUrl\":\"https:\\\/\\\/cannabisground.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/cannabis-ground.jpg\",\"width\":640,\"height\":168,\"caption\":\"Cannabis Ground\"},\"image\":{\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/annabisground\\\/\",\"https:\\\/\\\/x.com\\\/CannabisGround\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cannabisground.com\\\/es\\\/#\\\/schema\\\/person\\\/cf294a049b5af8df3bef74e1b4b1c770\",\"name\":\"Cannabis Ground\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g\",\"caption\":\"Cannabis Ground\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jim Belushi y su visi\u00f3n de la marihuana - Cannabis Ground","description":"Jim Belushi: Si hubi\u00e9ramos sabido antes sobre el cannabis lo que sabemos ahora, muchas personas que murieron podr\u00edan seguir vivas, incluido mi hermano.","robots":{"index":"index","follow":"nofollow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cannabisground.com\/es\/jim-belushi\/","og_locale":"es_ES","og_type":"article","og_title":"Jim Belushi y su visi\u00f3n de la marihuana","og_description":"Jim Belushi: Si hubi\u00e9ramos sabido antes sobre el cannabis lo que sabemos ahora, muchas personas que murieron podr\u00edan seguir vivas, incluido mi hermano.","og_url":"https:\/\/cannabisground.com\/es\/jim-belushi\/","og_site_name":"Cannabis Ground","article_publisher":"https:\/\/www.facebook.com\/annabisground\/","article_published_time":"2019-05-13T17:05:04+00:00","article_modified_time":"2019-05-13T17:07:30+00:00","og_image":[{"width":960,"height":960,"url":"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/Jim-Belushi-and-his-vision-of-marijuana-2.jpg","type":"image\/jpeg"}],"author":"Cannabis Ground","twitter_card":"summary_large_image","twitter_creator":"@CannabisGround","twitter_site":"@CannabisGround","twitter_misc":{"Escrito por":"Cannabis Ground","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cannabisground.com\/es\/jim-belushi\/#article","isPartOf":{"@id":"https:\/\/cannabisground.com\/es\/jim-belushi\/"},"author":{"name":"Cannabis Ground","@id":"https:\/\/cannabisground.com\/es\/#\/schema\/person\/cf294a049b5af8df3bef74e1b4b1c770"},"headline":"Jim Belushi y su visi\u00f3n de la marihuana","datePublished":"2019-05-13T17:05:04+00:00","dateModified":"2019-05-13T17:07:30+00:00","mainEntityOfPage":{"@id":"https:\/\/cannabisground.com\/es\/jim-belushi\/"},"wordCount":942,"publisher":{"@id":"https:\/\/cannabisground.com\/es\/#organization"},"image":{"@id":"https:\/\/cannabisground.com\/es\/jim-belushi\/#primaryimage"},"thumbnailUrl":"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/Jim-Belushi-and-his-vision-of-marijuana-2.jpg","articleSection":["Salud"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cannabisground.com\/es\/jim-belushi\/","url":"https:\/\/cannabisground.com\/es\/jim-belushi\/","name":"Jim Belushi y su visi\u00f3n de la marihuana - Cannabis Ground","isPartOf":{"@id":"https:\/\/cannabisground.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cannabisground.com\/es\/jim-belushi\/#primaryimage"},"image":{"@id":"https:\/\/cannabisground.com\/es\/jim-belushi\/#primaryimage"},"thumbnailUrl":"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/Jim-Belushi-and-his-vision-of-marijuana-2.jpg","datePublished":"2019-05-13T17:05:04+00:00","dateModified":"2019-05-13T17:07:30+00:00","description":"Jim Belushi: Si hubi\u00e9ramos sabido antes sobre el cannabis lo que sabemos ahora, muchas personas que murieron podr\u00edan seguir vivas, incluido mi hermano.","breadcrumb":{"@id":"https:\/\/cannabisground.com\/es\/jim-belushi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cannabisground.com\/es\/jim-belushi\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cannabisground.com\/es\/jim-belushi\/#primaryimage","url":"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/Jim-Belushi-and-his-vision-of-marijuana-2.jpg","contentUrl":"https:\/\/cannabisground.com\/wp-content\/uploads\/2019\/05\/Jim-Belushi-and-his-vision-of-marijuana-2.jpg","width":960,"height":960,"caption":"Jim Belushi"},{"@type":"BreadcrumbList","@id":"https:\/\/cannabisground.com\/es\/jim-belushi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cannabisground.com\/es\/"},{"@type":"ListItem","position":2,"name":"Jim Belushi y su visi\u00f3n de la marihuana"}]},{"@type":"WebSite","@id":"https:\/\/cannabisground.com\/es\/#website","url":"https:\/\/cannabisground.com\/es\/","name":"Cannabis Ground","description":"Marijuana and ...","publisher":{"@id":"https:\/\/cannabisground.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cannabisground.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cannabisground.com\/es\/#organization","name":"Cannabis Ground","url":"https:\/\/cannabisground.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cannabisground.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cannabisground.com\/wp-content\/uploads\/2018\/06\/cannabis-ground.jpg","contentUrl":"https:\/\/cannabisground.com\/wp-content\/uploads\/2018\/06\/cannabis-ground.jpg","width":640,"height":168,"caption":"Cannabis Ground"},"image":{"@id":"https:\/\/cannabisground.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/annabisground\/","https:\/\/x.com\/CannabisGround"]},{"@type":"Person","@id":"https:\/\/cannabisground.com\/es\/#\/schema\/person\/cf294a049b5af8df3bef74e1b4b1c770","name":"Cannabis Ground","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ea55571887fa86d320bebe20e7fbbb724968adbfa5e69318fea7179338ddcb21?s=96&d=mm&r=g","caption":"Cannabis Ground"}}]}},"_links":{"self":[{"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/posts\/2416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/comments?post=2416"}],"version-history":[{"count":0,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/posts\/2416\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/media\/2409"}],"wp:attachment":[{"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/media?parent=2416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/categories?post=2416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cannabisground.com\/es\/wp-json\/wp\/v2\/tags?post=2416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}